{"id":32355,"date":"2023-08-08T10:30:33","date_gmt":"2023-08-08T10:30:33","guid":{"rendered":"https:\/\/www.iceireland.com\/camp-d-ete-anglais-irlande\/residential-english-camp-ireland\/"},"modified":"2026-04-29T14:17:13","modified_gmt":"2026-04-29T14:17:13","slug":"residential-english-camp-ireland","status":"publish","type":"page","link":"https:\/\/www.iceireland.com\/fr\/camp-d-ete-anglais-irlande\/residential-english-camp-ireland\/","title":{"rendered":"Abbaye de Glenstal"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"32355\" class=\"elementor elementor-32355 elementor-18991\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-341fc93 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"341fc93\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d59ed98\" data-id=\"d59ed98\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f5f9da2 elementor-widget elementor-widget-heading\" data-id=\"f5f9da2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>Abbaye de Glenstal<\/b><br><b>Programme r\u00e9sidentiel 2026 <\/b> <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bf36b79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bf36b79\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ba962b0\" data-id=\"ba962b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7e1974 elementor-widget elementor-widget-heading\" data-id=\"a7e1974\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Limerick - Irlande<br>28 juin - 2 ao\u00fbt<br>11 - 17 ans<br>Anglais et programme multi-activit\u00e9s<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0672977 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0672977\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c933e5a\" data-id=\"c933e5a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8d3980 elementor-widget elementor-widget-text-editor\" data-id=\"c8d3980\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">L&rsquo;abbaye de Glenstal est l&rsquo;un des pensionnats les plus c\u00e9l\u00e8bres d&rsquo;Irlande. Les \u00e9tudiants qui participent \u00e0 notre camp d&rsquo;\u00e9t\u00e9 international pour jeunes \u00e0 Glenstal feront l&rsquo;exp\u00e9rience de la vie sur ce campus extraordinaire. Les \u00e9tudiants sont immerg\u00e9s dans le mode de vie d&rsquo;un internat irlandais historique et acqui\u00e8rent de nouvelles comp\u00e9tences de vie, se mettent au d\u00e9fi et gagnent en confiance, en respect et en ind\u00e9pendance.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6510db7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6510db7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ffc36f1\" data-id=\"ffc36f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-03853b3 elementor-widget elementor-widget-video\" data-id=\"03853b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;autoplay&quot;:&quot;yes&quot;,&quot;play_on_mobile&quot;:&quot;yes&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"autoplay\" title=\"Lecteur vid\u00e9o vimeo\" src=\"https:\/\/player.vimeo.com\/video\/229567737?autoplay=1&amp;playsinline=1&amp;color&amp;autopause=0&amp;loop=1&amp;muted=1&amp;title=0&amp;portrait=0&amp;byline=0#t=\"><\/iframe>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9e3a68 elementor-widget elementor-widget-spacer\" data-id=\"b9e3a68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b5261f4 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b5261f4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f42cb8a\" data-id=\"f42cb8a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d89a693 elementor-widget elementor-widget-text-editor\" data-id=\"d89a693\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: center;\"><span style=\"color: #ffffff;\"><strong>Une \u00e9cole prim\u00e9e<\/strong><\/span><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0ad1cc4\" data-id=\"0ad1cc4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c06d062 elementor-widget elementor-widget-text-editor\" data-id=\"c06d062\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: center;\"><b>Un campus magnifique et historique<\/b><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-17428fb\" data-id=\"17428fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f8b79a5 elementor-widget elementor-widget-text-editor\" data-id=\"f8b79a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span style=\"color: #ffffff;\"><strong>D\u00e9couvrir la Voie sauvage de l&rsquo;Atlantique<\/strong><\/span><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47a0841 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47a0841\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-735c1c9\" data-id=\"735c1c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a51dcf elementor-widget elementor-widget-spacer\" data-id=\"4a51dcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cad094 elementor-widget elementor-widget-heading\" data-id=\"9cad094\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le campus du ch\u00e2teau<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7dad8a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7dad8a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9469dab\" data-id=\"9469dab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90b0d58 elementor-widget elementor-widget-heading\" data-id=\"90b0d58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">D\u00e9couvrez le meilleur de Dublin et de l'Irlande<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c6b8710 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c6b8710\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5067aa8\" data-id=\"5067aa8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d330f3 elementor-widget elementor-widget-text-editor\" data-id=\"0d330f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">L&rsquo;abbaye de Glenstal est l&rsquo;un des pensionnats les plus c\u00e9l\u00e8bres d&rsquo;Irlande. Construite dans les ann\u00e9es 1830, elle a \u00e9t\u00e9 con\u00e7ue comme un ch\u00e2teau dans le style normand romantique du XIIe si\u00e8cle. L&rsquo;abbaye est situ\u00e9e sur un domaine de 500 acres avec des ruisseaux, des lacs et des chemins forestiers. Les \u00e9tudiants qui participent \u00e0 notre camp d&rsquo;\u00e9t\u00e9 international pour jeunes \u00e0 l&rsquo;Abbaye de Glenstal feront l&rsquo;exp\u00e9rience de la vie sur ce campus extraordinaire. Ils sont immerg\u00e9s dans le mode de vie d&rsquo;un internat irlandais historique et acqui\u00e8rent de nouvelles comp\u00e9tences de vie ainsi que de la confiance et de l&rsquo;ind\u00e9pendance.     Les \u00e9tudiants d\u00e9couvrent le meilleur de l&rsquo;ouest de l&rsquo;Irlande et participent \u00e0 des activit\u00e9s d&rsquo;aventure.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-251c897 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"251c897\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-89059b3\" data-id=\"89059b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99e7826 elementor-widget elementor-widget-gallery\" data-id=\"99e7826\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;justified&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;ideal_row_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:200,&quot;sizes&quot;:[]},&quot;ideal_row_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:150,&quot;sizes&quot;:[]},&quot;ideal_row_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:150,&quot;sizes&quot;:[]},&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2025-Banner-Photos-16.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"99e7826\" data-elementor-lightbox-title=\"_ICE Summer Camp 2025 Banner Photos (16)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzAwNjcsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9JQ0UtU3VtbWVyLUNhbXAtMjAyNS1CYW5uZXItUGhvdG9zLTE2LnBuZyIsInNsaWRlc2hvdyI6Ijk5ZTc4MjYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2025-Banner-Photos-16.png\" data-width=\"1500\" data-height=\"1000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2025-Banner-Photos-8.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"99e7826\" data-elementor-lightbox-title=\"_ICE Summer Camp 2025 Banner Photos (8)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzAwMDMsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9JQ0UtU3VtbWVyLUNhbXAtMjAyNS1CYW5uZXItUGhvdG9zLTgucG5nIiwic2xpZGVzaG93IjoiOTllNzgyNiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2025-Banner-Photos-8.png\" data-width=\"1500\" data-height=\"1000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-7.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"99e7826\" data-elementor-lightbox-title=\"ICE Summer Camp 2026 Banner Photos (7)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjk4OTksInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9JQ0UtU3VtbWVyLUNhbXAtMjAyNi1CYW5uZXItUGhvdG9zLTcucG5nIiwic2xpZGVzaG93IjoiOTllNzgyNiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-7.png\" data-width=\"1500\" data-height=\"1000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-ICE-Summer-Camp-Brochure-2026-13.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"99e7826\" data-elementor-lightbox-title=\"Copy of ICE Summer Camp Brochure 2026 (13)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzEwMDIsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9Db3B5LW9mLUlDRS1TdW1tZXItQ2FtcC1Ccm9jaHVyZS0yMDI2LTEzLnBuZyIsInNsaWRlc2hvdyI6Ijk5ZTc4MjYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-ICE-Summer-Camp-Brochure-2026-13.png\" data-width=\"1414\" data-height=\"1497\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-ICE-Summer-Camp-Brochure-2026-14.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"99e7826\" data-elementor-lightbox-title=\"Copy of ICE Summer Camp Brochure 2026 (14)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzEwMTAsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9Db3B5LW9mLUlDRS1TdW1tZXItQ2FtcC1Ccm9jaHVyZS0yMDI2LTE0LnBuZyIsInNsaWRlc2hvdyI6Ijk5ZTc4MjYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-ICE-Summer-Camp-Brochure-2026-14.png\" data-width=\"1414\" data-height=\"1481\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-ICE-Summer-Camp-Brochure-2026-15.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"99e7826\" data-elementor-lightbox-title=\"Copy of ICE Summer Camp Brochure 2026 (15)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzEwMjEsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9Db3B5LW9mLUlDRS1TdW1tZXItQ2FtcC1Ccm9jaHVyZS0yMDI2LTE1LnBuZyIsInNsaWRlc2hvdyI6Ijk5ZTc4MjYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-ICE-Summer-Camp-Brochure-2026-15.png\" data-width=\"1000\" data-height=\"1029\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-Junior-Summer-Camps-Brochure-2024-3.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"99e7826\" data-elementor-lightbox-title=\"Copy of Junior Summer Camps Brochure 2024 (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzEwMzAsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9Db3B5LW9mLUp1bmlvci1TdW1tZXItQ2FtcHMtQnJvY2h1cmUtMjAyNC0zLnBuZyIsInNsaWRlc2hvdyI6Ijk5ZTc4MjYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-Junior-Summer-Camps-Brochure-2024-3.png\" data-width=\"1414\" data-height=\"656\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0c143c elementor-widget elementor-widget-spacer\" data-id=\"f0c143c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f29a22 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f29a22\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60fcf00\" data-id=\"60fcf00\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d69a52 elementor-widget elementor-widget-heading\" data-id=\"7d69a52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Aper\u00e7u du programme de l'abbaye de Glenstal<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e20ca3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e20ca3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db2d8fa\" data-id=\"db2d8fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aea6867 elementor-widget elementor-widget-image\" data-id=\"aea6867\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1500\" height=\"1000\" src=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Glenstal-Abbey-Overview.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-31042\" alt=\"\" srcset=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Glenstal-Abbey-Overview.png 1500w, https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Glenstal-Abbey-Overview-300x200.png 300w, https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Glenstal-Abbey-Overview-1024x683.png 1024w, https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Glenstal-Abbey-Overview-768x512.png 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-748ab14 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"748ab14\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-55bc0e7\" data-id=\"55bc0e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e149df8 elementor-widget elementor-widget-gallery\" data-id=\"e149df8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;justified&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;ideal_row_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:200,&quot;sizes&quot;:[]},&quot;ideal_row_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:150,&quot;sizes&quot;:[]},&quot;ideal_row_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:150,&quot;sizes&quot;:[]},&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-9.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"e149df8\" data-elementor-lightbox-title=\"ICE Summer Camp 2026 Banner Photos (9)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjk5MTUsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9JQ0UtU3VtbWVyLUNhbXAtMjAyNi1CYW5uZXItUGhvdG9zLTkucG5nIiwic2xpZGVzaG93IjoiZTE0OWRmOCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-9.png\" data-width=\"1500\" data-height=\"1000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-8.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"e149df8\" data-elementor-lightbox-title=\"ICE Summer Camp 2026 Banner Photos (8)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjk5MDcsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9JQ0UtU3VtbWVyLUNhbXAtMjAyNi1CYW5uZXItUGhvdG9zLTgucG5nIiwic2xpZGVzaG93IjoiZTE0OWRmOCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-8.png\" data-width=\"1500\" data-height=\"1000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2025-Banner-Photos-4.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"e149df8\" data-elementor-lightbox-title=\"_ICE Summer Camp 2025 Banner Photos (4)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjk5NjMsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9JQ0UtU3VtbWVyLUNhbXAtMjAyNS1CYW5uZXItUGhvdG9zLTQucG5nIiwic2xpZGVzaG93IjoiZTE0OWRmOCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2025-Banner-Photos-4.png\" data-width=\"1500\" data-height=\"1000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-ICE-Summer-Camp-2026-Banner-Photos.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"e149df8\" data-elementor-lightbox-title=\"Copy of ICE Summer Camp 2026 Banner Photos\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzEwNTMsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9Db3B5LW9mLUlDRS1TdW1tZXItQ2FtcC0yMDI2LUJhbm5lci1QaG90b3MucG5nIiwic2xpZGVzaG93IjoiZTE0OWRmOCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-ICE-Summer-Camp-2026-Banner-Photos.png\" data-width=\"1105\" data-height=\"1000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-Junior-Summer-Camps-Brochure-2024-4.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"e149df8\" data-elementor-lightbox-title=\"Copy of Junior Summer Camps Brochure 2024 (4)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzEwNjIsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9Db3B5LW9mLUp1bmlvci1TdW1tZXItQ2FtcHMtQnJvY2h1cmUtMjAyNC00LnBuZyIsInNsaWRlc2hvdyI6ImUxNDlkZjgifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-Junior-Summer-Camps-Brochure-2024-4.png\" data-width=\"1365\" data-height=\"634\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2023\/10\/irish-dancing-p.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"e149df8\" data-elementor-lightbox-title=\"irish dancing - p\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjM3NTAsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzEwXC9pcmlzaC1kYW5jaW5nLXAuanBnIiwic2xpZGVzaG93IjoiZTE0OWRmOCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2023\/10\/irish-dancing-p.jpg\" data-width=\"999\" data-height=\"1500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-ICE-Summer-Camp-Brochure-2026-16.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"e149df8\" data-elementor-lightbox-title=\"Copy of ICE Summer Camp Brochure 2026 (16)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzEwNzEsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9Db3B5LW9mLUlDRS1TdW1tZXItQ2FtcC1Ccm9jaHVyZS0yMDI2LTE2LnBuZyIsInNsaWRlc2hvdyI6ImUxNDlkZjgifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-ICE-Summer-Camp-Brochure-2026-16.png\" data-width=\"1414\" data-height=\"1167\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-190ec5c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"190ec5c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-145da4e\" data-id=\"145da4e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fb4a0c elementor-widget elementor-widget-spacer\" data-id=\"6fb4a0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10a162d elementor-widget elementor-widget-heading\" data-id=\"10a162d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Exemple de programme sur deux semaines<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04f66af elementor-widget elementor-widget-image\" data-id=\"04f66af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1293\" height=\"920\" src=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-ICE-Summer-Camp-Brochure-2026-17.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-31083\" alt=\"\" srcset=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-ICE-Summer-Camp-Brochure-2026-17.png 1293w, https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-ICE-Summer-Camp-Brochure-2026-17-300x213.png 300w, https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-ICE-Summer-Camp-Brochure-2026-17-1024x729.png 1024w, https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-ICE-Summer-Camp-Brochure-2026-17-768x546.png 768w\" sizes=\"(max-width: 1293px) 100vw, 1293px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5be35caf elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5be35caf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;shape_divider_top&quot;:&quot;mountains&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-16ebf607\" data-id=\"16ebf607\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77279e3b elementor-widget elementor-widget-global elementor-global-34725 elementor-global-20855 elementor-widget-heading\" data-id=\"77279e3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ce qui est inclus<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a09c5bb elementor-widget__width-initial elementor-widget elementor-widget-global elementor-global-34716 elementor-global-20858 elementor-widget-text-editor\" data-id=\"7a09c5bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"font-size: 26px; font-weight: bold;\">Tout compris<\/span><\/p><p style=\"text-align: center;\">Nous croyons qu&rsquo;il est important d&rsquo;offrir un prix de cours tout compris. Tout est compris, il n&rsquo;y a pas de frais suppl\u00e9mentaires pour l&rsquo;inscription \u00e0 l&rsquo;\u00e9valuation ou l&rsquo;administration. Toutes les activit\u00e9s, les titres de transport, les droits d&rsquo;entr\u00e9e et les repas sont inclus.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47c4e0ce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47c4e0ce\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-42c21920\" data-id=\"42c21920\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52c8e0e6 elementor-position-inline-start elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-global elementor-global-34629 elementor-global-20876 elementor-widget-icon-box\" data-id=\"52c8e0e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-grow\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tClasses\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23723164 elementor-widget elementor-widget-text-editor\" data-id=\"23723164\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b style=\"color: var( --e-global-color-text );\">Frais de scolarit\u00e9 :  <br><\/b><span style=\"color: var( --e-global-color-text );\"><br>Nous avons un programme sp\u00e9cialement con\u00e7u pour les juniors afin d&rsquo;encourager la progression et la confiance de votre enfant. Nous croyons aux mat\u00e9riaux r\u00e9els et \u00e0 la n\u00e9cessit\u00e9 d&rsquo;apprendre \u00e0 aimer la langue en la vivant. Les classes sont internationales et comptent un maximum de 15 \u00e9tudiants par classe.  <\/span><\/p><ul><li>Heures : 15 heures de cours par semaine<\/li><li>Horaires : 9 h 15 &#8211; 12 h 30 chaque jour de la semaine avec une pause de 15 minutes.<span style=\"font-weight: bold;\"> <\/span><\/li><li>Taille maximale de la classe :<span style=\"font-weight: bold;\"> <span style=\"font-weight: 400;\">15 \u00e9tudiants<\/span><br><\/span><\/li><li>Niveaux d&rsquo;entr\u00e9e : Pr\u00e9-interm\u00e9diaire (A2) \u00e0 avanc\u00e9 (C1).<\/li><\/ul><p> <\/p><p><strong>Programme interculturel irlandais pour les adolescents<\/strong><\/p><p>Dans le cadre de nos efforts continus pour maintenir des classes de haute qualit\u00e9 et pour am\u00e9liorer l&rsquo;exp\u00e9rience interculturelle de nos \u00e9tudiants, nous avons des le\u00e7ons hebdomadaires appel\u00e9es Programme interculturel pour les adolescents. Des adolescents irlandais se joignent aux cours pour diriger un exercice aux c\u00f4t\u00e9s du professeur, ce qui permet \u00e0 nos \u00e9l\u00e8ves d&rsquo;entrer en contact avec des adolescents irlandais, leurs pairs, et nous avons re\u00e7u une r\u00e9ponse incroyablement positive \u00e0 ce programme. <\/p><p><b>Rapport et certificat de l&rsquo;\u00e9tudiant<\/b><\/p><p>Les \u00e9tudiants re\u00e7oivent un certificat d&rsquo;assiduit\u00e9 et de r\u00e9ussite \u00e0 la fin de leur cours, ainsi qu&rsquo;un rapport individuel de leur professeur sur leurs progr\u00e8s.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5499068a\" data-id=\"5499068a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c741a11 elementor-position-inline-start elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-global elementor-global-34621 elementor-global-20879 elementor-widget-icon-box\" data-id=\"2c741a11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-grow\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tH\u00e9bergement\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0d187e elementor-widget elementor-widget-text-editor\" data-id=\"b0d187e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"node-camp-full__field-about-the-package about-section__about-the-package-component\"><div class=\"node-camp-full__field-about-the-package-item about-section__item about-section__content\"><p><b><strong>H\u00e9bergement : <\/strong><\/b>R\u00e9sidentiel<\/p><p>\u00c0 l&rsquo;abbaye de Glenstal, notre logement r\u00e9sidentiel se trouve dans l&rsquo;\u00e9cole, de sorte que les \u00e9tudiants ont l&rsquo;impression de vivre sur un campus historique. Les \u00e9tudiants du m\u00eame \u00e2ge et du m\u00eame sexe sont log\u00e9s ensemble et nous m\u00e9langeons les nationalit\u00e9s. Les chambres peuvent g\u00e9n\u00e9ralement accueillir de 2 \u00e0 8 \u00e9tudiants. Les toilettes et les douches sont adjacentes aux chambres. Le lavage du linge des \u00e9tudiants une fois par semaine est inclus.   <\/p><p><b>Repas<\/b><\/p><p>\u00c0 l&rsquo;abbaye de Glenstal, la nourriture est l&rsquo;un des points forts du s\u00e9jour des \u00e9tudiants. Le personnel de restauration propose des repas chauds au petit-d\u00e9jeuner, au d\u00e9jeuner et au d\u00eener, ainsi qu&rsquo;une collation le soir.  <\/p><p>La nourriture est de grande qualit\u00e9, d&rsquo;origine locale et tr\u00e8s vari\u00e9e.  <span style=\"color: var( --e-global-color-text );\">A leur arriv\u00e9e, les \u00e9tudiants re\u00e7oivent \u00e9galement une bouteille d&rsquo;eau rechargeable pour leur s\u00e9jour.  <\/span><\/p><p>Nous pouvons r\u00e9pondre \u00e0 des besoins di\u00e9t\u00e9tiques particuliers sur demande.<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7ec9bff5\" data-id=\"7ec9bff5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cbcb4a9 elementor-position-inline-start elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-global elementor-global-34592 elementor-global-20882 elementor-widget-icon-box\" data-id=\"3cbcb4a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-grow\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tActivit\u00e9s\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4677eaef elementor-widget elementor-widget-text-editor\" data-id=\"4677eaef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Activit\u00e9s en semaine<\/b><\/p><p>Les \u00e9tudiants ont un programme complet d&rsquo;activit\u00e9s et de visites. Nous pensons qu&rsquo;il est essentiel pour les \u00e9tudiants en r\u00e9sidence d&rsquo;avoir de nombreuses possibilit\u00e9s de visites et d&rsquo;activit\u00e9s en dehors du site afin de garantir un s\u00e9jour enrichissant et agr\u00e9able en Irlande. <\/p><p>Les \u00e9tudiants sortent du campus 2 \u00e0 3 apr\u00e8s-midi par semaine pour participer \u00e0 des excursions mixtes comprenant des activit\u00e9s d&rsquo;aventure. Sur place, nous organisons des activit\u00e9s sportives et de plein air. <\/p><p>En outre, nous avons un programme de comp\u00e9tences en soir\u00e9e pour acqu\u00e9rir de nouvelles comp\u00e9tences et d&rsquo;autres activit\u00e9s ludiques et de renforcement de l&rsquo;esprit d&rsquo;\u00e9quipe.<\/p><p><b>Excursions d&rsquo;une journ\u00e9e<\/b><\/p><p>L&rsquo;abbaye de Glenstal est situ\u00e9e dans la r\u00e9gion pittoresque de l&rsquo;ouest de l&rsquo;Irlande et nos \u00e9tudiants ont la possibilit\u00e9 de suivre la Wild Atlantic Way et de voir les points forts de cette c\u00f4te \u00e9tonnante. Les \u00e9tudiants b\u00e9n\u00e9ficient d&rsquo;une excursion d&rsquo;une journ\u00e9e compl\u00e8te chaque week-end. <\/p><p>Exemples de circuits : Falaises de Moher, p\u00e9ninsule de Dingle, ville de Galway, centre ville de Dublin.<\/p><p><b>Journ\u00e9e de d\u00e9tente<\/b><\/p><p>Le dimanche, nos \u00e9tudiants ont la possibilit\u00e9 de se d\u00e9tendre et de participer \u00e0 des activit\u00e9s amusantes sur le campus.<\/p><p><b>Transport<\/b><\/p><p>Tous les transports se font en autocar priv\u00e9 pour nos activit\u00e9s.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a97a5f3 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a97a5f3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5edeb94d\" data-id=\"5edeb94d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6131639b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6131639b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c43c53\" data-id=\"7c43c53\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3134d40a elementor-widget elementor-widget-global elementor-global-34576 elementor-global-20888 elementor-widget-heading\" data-id=\"3134d40a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Questions fr\u00e9quemment pos\u00e9es<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-368edd34 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"368edd34\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-2e17b697\" data-id=\"2e17b697\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-35414d3a\" data-id=\"35414d3a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f39afd elementor-widget elementor-widget-toggle\" data-id=\"4f39afd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8301\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8301\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quel sera le calendrier ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8301\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8301\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Les \u00e9tudiants sont occup\u00e9s toute la journ\u00e9e et ont un emploi du temps agr\u00e9able avec du temps libre entre les activit\u00e9s. Petit-d\u00e9jeuner, cours d&rsquo;anglais, d\u00e9jeuner, activit\u00e9, d\u00eener, activit\u00e9 du soir\/programme de comp\u00e9tences, collation, coucher. <\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8302\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-8302\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quelle est la r\u00e9partition des nationalit\u00e9s ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8302\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-8302\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">\u00c0 tout moment, entre 15 et 27 nationalit\u00e9s sont repr\u00e9sent\u00e9es dans notre \u00e9cole.<\/p>\n<p>En savoir plus sur le <a href=\"https:\/\/www.iceireland.com\/fr\/nationality-mix\/\">m\u00e9lange des nationalit\u00e9s<\/a>.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8303\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-8303\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Y a-t-il des frais suppl\u00e9mentaires ou additionnels et de combien d'argent de poche l'\u00e9l\u00e8ve a-t-il besoin ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8303\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-8303\"><div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Le programme est tout compris, sans frais suppl\u00e9mentaires. La plupart des \u00e9tudiants apportent entre 80 et 100 euros d&rsquo;argent de poche par semaine pour les souvenirs, les friandises, etc. <\/p>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8304\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-8304\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Comment choisir les dates et heures d'arriv\u00e9e et de d\u00e9part ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8304\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-8304\"><div class=\"hidden-content\">\n<p>Pour un s\u00e9jour de 2 semaines, nous nous basons sur 14 nuits d&rsquo;h\u00e9bergement, pour un s\u00e9jour de 3 semaines sur 21 nuits et pour un s\u00e9jour de 4 semaines sur 28 nuits. La plupart des \u00e9tudiants arrivent le dimanche et repartent le dimanche correspondant.  Nous proposons un service d&rsquo;accueil et de transfert \u00e0 l&rsquo;a\u00e9roport. Nous pouvons organiser des transferts a\u00e9roportuaires pour des arriv\u00e9es\/d\u00e9parts entre 8h et 20h le dimanche. Si vous avez besoin de dates ou de transferts en dehors de ces horaires, veuillez nous consulter pour conna\u00eetre les disponibilit\u00e9s et les tarifs. <\/p>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8305\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-8305\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Combien d'\u00e9l\u00e8ves y aura-t-il dans une classe ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8305\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-8305\"><div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Le nombre maximum d&rsquo;\u00e9l\u00e8ves par classe est de 15, la moyenne \u00e9tant de 13 \u00e9l\u00e8ves par classe.<\/p>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8306\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-8306\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quelles sont les qualifications de vos enseignants ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8306\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-8306\"><div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Tous nos enseignants sont titulaires d&rsquo;une licence et d&rsquo;une qualification compl\u00e9mentaire d&rsquo;enseignement de l&rsquo;anglais. Tous nos enseignants sont reconnus comme des professeurs d&rsquo;anglais qualifi\u00e9s par l&rsquo;ACELS.<\/p>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8307\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-8307\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Comment placer les \u00e9l\u00e8ves dans le niveau d'anglais qui leur correspond ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8307\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-8307\"><div class=\"hidden-content\">\n<p>Nous testons les \u00e9l\u00e8ves avant leur arriv\u00e9e et le premier jour, leur professeur v\u00e9rifiera s&rsquo;ils sont dans le bon niveau.<\/p>\n<p>Nous suivons les progr\u00e8s des \u00e9l\u00e8ves en leur faisant passer des tests hebdomadaires.<\/p>\n<p>Les \u00e9l\u00e8ves peuvent changer de niveau si nous estimons qu&rsquo;ils ne sont pas dans le bon niveau.<\/p>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8308\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-8308\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Combien de niveaux d'anglais avez-vous ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8308\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-8308\"><div class=\"hidden-content\">\n<p>Tous nos programmes juniors sont align\u00e9s sur le CECR (Cadre europ\u00e9en commun de r\u00e9f\u00e9rence). Nous proposons des niveaux allant de A2 \u00e0 C1, pour des apprenants de niveau pr\u00e9-interm\u00e9diaire \u00e0 avanc\u00e9. <\/p>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8309\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-8309\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Disposez-vous d'un num\u00e9ro de contact d'urgence et d'une aide disponible ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8309\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-8309\"><div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Oui, nous disposons d&rsquo;un num\u00e9ro d&rsquo;urgence 24 heures sur 24 et nous sommes toujours disponibles pour vous aider.<\/p>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83010\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-83010\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Que se passe-t-il le jour de la rentr\u00e9e ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83010\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-83010\"><div class=\"hidden-content\">\n<p class=\"hiddenContentp\">\u00c0 leur arriv\u00e9e, les \u00e9tudiants seront conduits \u00e0 leur chambre et recevront une visite du campus ainsi que des informations pertinentes concernant la vie sur le campus, les cours et les activit\u00e9s. On leur indiquera \u00e9galement leur salle de classe et le point de rencontre pour les activit\u00e9s du lendemain. Ils participeront ensuite aux activit\u00e9s pr\u00e9vues.  <\/p>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83011\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-83011\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Pouvez-vous fournir une lettre d'invitation \u00e0 des fins de visa ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83011\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-83011\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Oui, nous fournissons des lettres \u00e0 tous les \u00e9tudiants provenant de pays hors UE qui ont besoin d&rsquo;un visa pour entrer en Irlande.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83012\" class=\"elementor-tab-title\" data-tab=\"12\" role=\"button\" aria-controls=\"elementor-tab-content-83012\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Y a-t-il un wifi gratuit dans l'\u00e9cole ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83012\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"12\" role=\"region\" aria-labelledby=\"elementor-tab-title-83012\"><p>Oui<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83013\" class=\"elementor-tab-title\" data-tab=\"13\" role=\"button\" aria-controls=\"elementor-tab-content-83013\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Les t\u00e9l\u00e9phones portables sont-ils autoris\u00e9s ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83013\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"13\" role=\"region\" aria-labelledby=\"elementor-tab-title-83013\"><p>Oui, mais pendant les cours, les activit\u00e9s et apr\u00e8s l&rsquo;extinction des feux, les t\u00e9l\u00e9phones portables doivent \u00eatre \u00e9teints. Notre camp est ax\u00e9 sur la communication et la ma\u00eetrise de la langue. <\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83014\" class=\"elementor-tab-title\" data-tab=\"14\" role=\"button\" aria-controls=\"elementor-tab-content-83014\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quand dois-je payer les frais ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83014\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"14\" role=\"region\" aria-labelledby=\"elementor-tab-title-83014\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Un acompte de 200 euros est vers\u00e9 lors de la r\u00e9servation. Le reste des frais est d\u00fb 4 semaines avant l&rsquo;arriv\u00e9e. <\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83015\" class=\"elementor-tab-title\" data-tab=\"15\" role=\"button\" aria-controls=\"elementor-tab-content-83015\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quelle est la politique de remboursement ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83015\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"15\" role=\"region\" aria-labelledby=\"elementor-tab-title-83015\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<ol>\n<li>Politique d&rsquo;annulation et de remboursement :\n<p>Notre \u00ab\u00a0Garantie de r\u00e9servation en toute confiance\u00a0\u00bb est con\u00e7ue pour offrir une certaine flexibilit\u00e9 tout en garantissant le meilleur service possible \u00e0 tous les \u00e9tudiants. Nous recommandons vivement aux \u00e9tudiants\/parents\/tuteurs\/organisateurs de groupes de souscrire une assurance voyage afin de se pr\u00e9munir contre tout changement impr\u00e9vu dans leurs projets de voyage.   <\/p>\n<p>Annulation 7 jours ou plus avant l&rsquo;arriv\u00e9e &#8211; Remboursement int\u00e9gral<\/p>\n<p>Annulation 3 \u00e0 6 jours avant l&rsquo;arriv\u00e9e &#8211; remboursement de 50% du montant total de la r\u00e9servation<\/p>\n<p>Annulation 1 &#8211; 2 jours avant l&rsquo;arriv\u00e9e &#8211; Pas de remboursement<\/p>\n<p><strong>Remarques importantes :<\/strong><\/p>\n<p>Toute annulation doit \u00eatre faite par \u00e9crit \u00e0 l&rsquo;adresse <a href=\"mailto:info@iceireland.com\">info@iceireland.com et faire l&rsquo;objet d&rsquo;un accus\u00e9 de r\u00e9ception par le Coll\u00e8ge .<\/a> <\/p>\n<ul>\n<li>Les remboursements seront effectu\u00e9s dans les 7 \u00e0 10 jours ouvrables suivant la confirmation de l&rsquo;annulation.<\/li>\n<li>Aucun remboursement ne sera accord\u00e9 en cas de non-pr\u00e9sentation ou de d\u00e9part pr\u00e9matur\u00e9 des cours.<\/li>\n<li>Aux fins de notre politique de remboursement, le terme \u00ab\u00a0arriv\u00e9e\u00a0\u00bb est fix\u00e9 \u00e0 10 heures du matin le jour de l&rsquo;arriv\u00e9e, quelle que soit l&rsquo;heure d&rsquo;arriv\u00e9e effective.<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83016\" class=\"elementor-tab-title\" data-tab=\"16\" role=\"button\" aria-controls=\"elementor-tab-content-83016\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">La blanchisserie de mon enfant est-elle faite pour lui ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83016\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"16\" role=\"region\" aria-labelledby=\"elementor-tab-title-83016\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Oui, nous faisons la lessive une fois par semaine pour tous les \u00e9tudiants.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83017\" class=\"elementor-tab-title\" data-tab=\"17\" role=\"button\" aria-controls=\"elementor-tab-content-83017\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Recevrai-je une liste de colisage ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83017\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"17\" role=\"region\" aria-labelledby=\"elementor-tab-title-83017\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\"><span style=\"color: #7a7a7a; font-family: Catamaran, sans-serif; font-size: 17px; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 300; letter-spacing: normal; orphans: 2; text-align: left; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-thickness: initial; text-decoration-style: initial; text-decoration-color: initial; display: inline !important; float: none;\">Oui, vous recevrez une liste de colisage dans le manuel de l&rsquo;\u00e9tudiant avant votre arriv\u00e9e.<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"exp-col-content-holder\"> <\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83018\" class=\"elementor-tab-title\" data-tab=\"18\" role=\"button\" aria-controls=\"elementor-tab-content-83018\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Mon enfant peut-il sortir seul du campus ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83018\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"18\" role=\"region\" aria-labelledby=\"elementor-tab-title-83018\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Non, les \u00e9tudiants ne sont pas autoris\u00e9s \u00e0 quitter le campus sans permission, sauf le dimanche o\u00f9 ils peuvent visiter le village local avec la permission de notre \u00e9quipe.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"exp-col-content-holder\"> <\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83019\" class=\"elementor-tab-title\" data-tab=\"19\" role=\"button\" aria-controls=\"elementor-tab-content-83019\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Le prix inclut-il les vols ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83019\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"19\" role=\"region\" aria-labelledby=\"elementor-tab-title-83019\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Non, vous devez r\u00e9server vos propres vols.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83020\" class=\"elementor-tab-title\" data-tab=\"20\" role=\"button\" aria-controls=\"elementor-tab-content-83020\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">La plupart des \u00e9tudiants viennent-ils en groupe ou se rendent-ils individuellement \u00e0 la CIE ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83020\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"20\" role=\"region\" aria-labelledby=\"elementor-tab-title-83020\"><p><span style=\"color: #7a7a7a; font-family: Catamaran, sans-serif; font-size: 17px; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 300; letter-spacing: normal; orphans: 2; text-align: left; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-thickness: initial; text-decoration-style: initial; text-decoration-color: initial; display: inline !important; float: none;\">Environ 40 % de nos \u00e9tudiants arrivent en tant qu&rsquo;individus et le reste en tant que groupes pr\u00e9-organis\u00e9s. Les individus seront plac\u00e9s ensemble pour les activit\u00e9s de l&rsquo;apr\u00e8s-midi et sont s\u00e9par\u00e9s par \u00e2ge, de sorte qu&rsquo;il est facile de se faire de nouveaux amis. <\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83021\" class=\"elementor-tab-title\" data-tab=\"21\" role=\"button\" aria-controls=\"elementor-tab-content-83021\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Accepterez-vous un enfant de 10 ans ou de 18 ans ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83021\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"21\" role=\"region\" aria-labelledby=\"elementor-tab-title-83021\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<div class=\"elementor-toggle-item\">\n<div id=\"elementor-tab-content-58821\" class=\"elementor-tab-content elementor-clearfix elementor-active\" role=\"tabpanel\" data-tab=\"21\" aria-labelledby=\"elementor-tab-title-58821\">\n<div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<div class=\"elementor-toggle-item\">\n<div id=\"elementor-tab-content-10721\" class=\"elementor-tab-content elementor-clearfix elementor-active\" role=\"tabpanel\" data-tab=\"21\" aria-labelledby=\"elementor-tab-title-10721\">\n<div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p>Non, notre tranche d&rsquo;\u00e2ge va de 11 \u00e0 17 ans. Toutefois, dans certaines circonstances, si un enfant atteint l&rsquo;\u00e2ge de 18 ans et qu&rsquo;il est encore au lyc\u00e9e jusqu&rsquo;\u00e0 l&rsquo;\u00e9t\u00e9 du camp, nous pouvons l&rsquo;accepter dans le programme. <\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-toggle-item\"> <\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83022\" class=\"elementor-tab-title\" data-tab=\"22\" role=\"button\" aria-controls=\"elementor-tab-content-83022\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Recevrai-je un dossier d'information avant mon arriv\u00e9e ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83022\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"22\" role=\"region\" aria-labelledby=\"elementor-tab-title-83022\"><p><span style=\"color: #7a7a7a; font-family: Catamaran, sans-serif; font-size: 17px; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 300; letter-spacing: normal; orphans: 2; text-align: left; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-thickness: initial; text-decoration-style: initial; text-decoration-color: initial; display: inline !important; float: none;\">Oui, tous les \u00e9tudiants re\u00e7oivent un manuel de l&rsquo;\u00e9tudiant qui comprend une liste de colisage avant l&rsquo;arriv\u00e9e.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83023\" class=\"elementor-tab-title\" data-tab=\"23\" role=\"button\" aria-controls=\"elementor-tab-content-83023\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Que faire si mon enfant n'est pas satisfait de sa chambre, de son camarade de chambre, de sa classe ou de tout autre aspect de son s\u00e9jour ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83023\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"23\" role=\"region\" aria-labelledby=\"elementor-tab-title-83023\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\"><span style=\"color: #7a7a7a; font-family: Catamaran, sans-serif; font-size: 17px; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 300; letter-spacing: normal; orphans: 2; text-align: left; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-thickness: initial; text-decoration-style: initial; text-decoration-color: initial; display: inline !important; float: none;\">Nous sommes toujours l\u00e0 pour vous aider et vous assister de toutes les mani\u00e8res possibles pour que votre enfant soit heureux.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83024\" class=\"elementor-tab-title\" data-tab=\"24\" role=\"button\" aria-controls=\"elementor-tab-content-83024\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Mon enfant aura-t-il du temps libre ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83024\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"24\" role=\"region\" aria-labelledby=\"elementor-tab-title-83024\"><div>\n<div>\n<p><span style=\"color: #7a7a7a; font-family: Catamaran, sans-serif; font-size: 17px; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 300; letter-spacing: normal; orphans: 2; text-align: left; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-thickness: initial; text-decoration-style: initial; text-decoration-color: initial; display: inline !important; float: none;\">Bien qu&rsquo;il y ait du personnel 24 heures sur 24 sur le campus, les \u00e9tudiants ne sont pas toujours surveill\u00e9s et ont du temps libre.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83025\" class=\"elementor-tab-title\" data-tab=\"25\" role=\"button\" aria-controls=\"elementor-tab-content-83025\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Comment se d\u00e9roule le transfert de mon enfant \u00e0 l'a\u00e9roport ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83025\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"25\" role=\"region\" aria-labelledby=\"elementor-tab-title-83025\"><p>Un membre de notre personnel attend votre enfant \u00e0 l&rsquo;a\u00e9roport avec une pancarte. Nous nous assurons \u00e9galement d&rsquo;avoir le num\u00e9ro de portable de votre enfant, ainsi que le num\u00e9ro de nos chauffeurs et notre num\u00e9ro d&rsquo;urgence en cas de retard, etc. <\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83026\" class=\"elementor-tab-title\" data-tab=\"26\" role=\"button\" aria-controls=\"elementor-tab-content-83026\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Aiderez-vous mon enfant \u00e0 s'enregistrer \u00e0 l'a\u00e9roport ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83026\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"26\" role=\"region\" aria-labelledby=\"elementor-tab-title-83026\"><div class=\"elementor-toggle-item\">\n<div id=\"elementor-tab-content-10726\" class=\"elementor-tab-content elementor-clearfix elementor-active\" role=\"tabpanel\" data-tab=\"26\" aria-labelledby=\"elementor-tab-title-10726\">\n<div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Oui, il suffit de demander de l&rsquo;aide au moment du d\u00e9part et notre chauffeur aidera votre enfant \u00e0 s&rsquo;enregistrer et l&rsquo;am\u00e8nera jusqu&rsquo;au poste de s\u00e9curit\u00e9 si vous le souhaitez, sans frais suppl\u00e9mentaires.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-toggle-item\"> <\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83027\" class=\"elementor-tab-title\" data-tab=\"27\" role=\"button\" aria-controls=\"elementor-tab-content-83027\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Pouvez-vous enregistrer mon enfant au d\u00e9part avec un service pour mineurs non accompagn\u00e9s ou remplir le formulaire d'indemnisation pour Aerlingus, y a-t-il un co\u00fbt suppl\u00e9mentaire ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83027\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"27\" role=\"region\" aria-labelledby=\"elementor-tab-title-83027\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\"><span style=\"color: #7a7a7a; font-family: Catamaran, sans-serif; font-size: 17px; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 300; letter-spacing: normal; orphans: 2; text-align: left; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-thickness: initial; text-decoration-style: initial; text-decoration-color: initial; display: inline !important; float: none;\">Oui, nous sommes heureux de proc\u00e9der \u00e0 des inscriptions sans frais suppl\u00e9mentaires. Veuillez nous en informer au moment de la r\u00e9servation.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83028\" class=\"elementor-tab-title\" data-tab=\"28\" role=\"button\" aria-controls=\"elementor-tab-content-83028\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Pouvez-vous prendre en charge des r\u00e9gimes alimentaires particuliers ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83028\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"28\" role=\"region\" aria-labelledby=\"elementor-tab-title-83028\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<div class=\"elementor-toggle-item\">\n<div id=\"elementor-tab-content-10728\" class=\"elementor-tab-content elementor-clearfix elementor-active\" role=\"tabpanel\" data-tab=\"28\" aria-labelledby=\"elementor-tab-title-10728\">\n<div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Oui, nous pouvons r\u00e9pondre \u00e0 certains r\u00e9gimes sp\u00e9ciaux dans la limite du raisonnable. Il vous suffit de v\u00e9rifier aupr\u00e8s de nous avant la r\u00e9servation et un suppl\u00e9ment sera parfois appliqu\u00e9.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-toggle-item\"> <\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83029\" class=\"elementor-tab-title\" data-tab=\"29\" role=\"button\" aria-controls=\"elementor-tab-content-83029\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Mon enfant peut-il prendre un taxi de l'a\u00e9roport \u00e0 la r\u00e9sidence directement si nous n'optons pas pour les transferts de l'a\u00e9roport ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83029\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"29\" role=\"region\" aria-labelledby=\"elementor-tab-title-83029\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<div class=\"elementor-toggle-item\">\n<div id=\"elementor-tab-content-10729\" class=\"elementor-tab-content elementor-clearfix elementor-active\" role=\"tabpanel\" data-tab=\"29\" aria-labelledby=\"elementor-tab-title-10729\">\n<div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Oui, c&rsquo;est votre choix. Cependant, pour des raisons de s\u00e9curit\u00e9, nous conseillons \u00e0 tous les enfants de se faire accueillir \u00e0 l&rsquo;a\u00e9roport par notre service de transfert. De plus, les services d&rsquo;immigration de l&rsquo;a\u00e9roport de Dublin indiquent que tous les enfants de moins de 18 ans doivent \u00eatre accueillis par quelqu&rsquo;un \u00e0 l&rsquo;a\u00e9roport de Dublin.  <\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-toggle-item\"> <\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83030\" class=\"elementor-tab-title\" data-tab=\"30\" role=\"button\" aria-controls=\"elementor-tab-content-83030\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Puis-je d\u00e9poser mon enfant directement \u00e0 la r\u00e9sidence ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83030\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"30\" role=\"region\" aria-labelledby=\"elementor-tab-title-83030\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p>Oui, nous coordonnerons une heure avec la r\u00e9sidence.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83031\" class=\"elementor-tab-title\" data-tab=\"31\" role=\"button\" aria-controls=\"elementor-tab-content-83031\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quel type de certificat mon enfant recevra-t-il \u00e0 la fin du cours ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83031\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"31\" role=\"region\" aria-labelledby=\"elementor-tab-title-83031\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Votre enfant recevra un certificat de r\u00e9ussite et d&rsquo;assiduit\u00e9 ainsi qu&rsquo;un rapport individuel des enseignants sur ses progr\u00e8s.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83032\" class=\"elementor-tab-title\" data-tab=\"32\" role=\"button\" aria-controls=\"elementor-tab-content-83032\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quelle sera la taille des chambres des \u00e9tudiants ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83032\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"32\" role=\"region\" aria-labelledby=\"elementor-tab-title-83032\"><p>A Glenstal, les chambres sont pr\u00e9vues pour 2 \u00e0 8 \u00e9tudiants.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83033\" class=\"elementor-tab-title\" data-tab=\"33\" role=\"button\" aria-controls=\"elementor-tab-content-83033\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Les chambres sont-elles \u00e9quip\u00e9es d'une salle de bain ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83033\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"33\" role=\"region\" aria-labelledby=\"elementor-tab-title-83033\"><p>La plupart des chambres ne disposent pas de salle de bains, mais de toilettes et de douches communes.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83034\" class=\"elementor-tab-title\" data-tab=\"34\" role=\"button\" aria-controls=\"elementor-tab-content-83034\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Les gar\u00e7ons et les filles sont-ils r\u00e9partis dans des zones diff\u00e9rentes de la r\u00e9sidence ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83034\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"34\" role=\"region\" aria-labelledby=\"elementor-tab-title-83034\"><p>Oui, les gar\u00e7ons et les filles se trouvent dans des zones diff\u00e9rentes de la r\u00e9sidence.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83035\" class=\"elementor-tab-title\" data-tab=\"35\" role=\"button\" aria-controls=\"elementor-tab-content-83035\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">La r\u00e9sidence est-elle situ\u00e9e dans le Coll\u00e8ge\/l'Abbaye ou dans un autre b\u00e2timent ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83035\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"35\" role=\"region\" aria-labelledby=\"elementor-tab-title-83035\"><p>Oui, nos deux r\u00e9sidences se trouvent dans le b\u00e2timent principal.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83036\" class=\"elementor-tab-title\" data-tab=\"36\" role=\"button\" aria-controls=\"elementor-tab-content-83036\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Y a-t-il un petit d\u00e9jeuner, un d\u00e9jeuner et un d\u00eener chauds ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83036\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"36\" role=\"region\" aria-labelledby=\"elementor-tab-title-83036\"><div class=\"elementor-toggle-item\">\n<div id=\"elementor-tab-content-10736\" class=\"elementor-tab-content elementor-clearfix elementor-active\" role=\"tabpanel\" data-tab=\"36\" aria-labelledby=\"elementor-tab-title-10736\">\n<p>Oui, il y a toujours une option chaude disponible pour le petit-d\u00e9jeuner, le d\u00e9jeuner et le d\u00eener, et les \u00e9l\u00e8ves ont une collation avant de se coucher.<\/p>\n<\/div>\n<\/div>\n<div class=\"elementor-toggle-item\"> <\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83037\" class=\"elementor-tab-title\" data-tab=\"37\" role=\"button\" aria-controls=\"elementor-tab-content-83037\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">L'eau est-elle toujours disponible ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83037\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"37\" role=\"region\" aria-labelledby=\"elementor-tab-title-83037\"><p>Oui, \u00e0 leur arriv\u00e9e, les \u00e9l\u00e8ves re\u00e7oivent une bouteille d&rsquo;eau \u00e9cologique qu&rsquo;ils peuvent remplir tout au long de la journ\u00e9e \u00e0 l&rsquo;une des nombreuses stations d&rsquo;eau de l&rsquo;\u00e9cole.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83038\" class=\"elementor-tab-title\" data-tab=\"38\" role=\"button\" aria-controls=\"elementor-tab-content-83038\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Comment la r\u00e9sidence est-elle surveill\u00e9e la nuit ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83038\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"38\" role=\"region\" aria-labelledby=\"elementor-tab-title-83038\"><p>Les ma\u00eetres de maison dorment dans des chambres situ\u00e9es \u00e0 c\u00f4t\u00e9 de chaque espace r\u00e9serv\u00e9 aux \u00e9tudiants et sont de garde. En outre, un surveillant de nuit est toujours \u00e9veill\u00e9 pendant la nuit. <\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83039\" class=\"elementor-tab-title\" data-tab=\"39\" role=\"button\" aria-controls=\"elementor-tab-content-83039\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Qu'est-ce que le CECR et comment comprendre les niveaux - A2, B1, B2, C1.<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83039\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"39\" role=\"region\" aria-labelledby=\"elementor-tab-title-83039\"><p>Le CECR est le Cadre europ\u00e9en commun de r\u00e9f\u00e9rence pour les langues, qui a \u00e9t\u00e9 d\u00e9velopp\u00e9 pour fournir une base commune pour la description explicite des objectifs, du contenu et des m\u00e9thodes dans l&rsquo;enseignement des langues secondes\/\u00e9trang\u00e8res. Tous les programmes de l&rsquo;ICE sont align\u00e9s sur cette \u00e9chelle, nous proposons des cours du niveau A2 au niveau C1. Pour plus d&rsquo;informations sur le CECR, veuillez <a href=\"https:\/\/www.coe.int\/en\/web\/common-european-framework-reference-languages\/level-descriptions\" target=\"_blank\" rel=\"noopener\">cliquer ici<\/a>.  <\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83040\" class=\"elementor-tab-title\" data-tab=\"40\" role=\"button\" aria-controls=\"elementor-tab-content-83040\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Les programmes de la CIE sont-ils align\u00e9s sur le CECR ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83040\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"40\" role=\"region\" aria-labelledby=\"elementor-tab-title-83040\"><p>Oui, tous nos programmes sont align\u00e9s sur le CECR et nous proposons des niveaux allant de A2 \u00e0 C1, c&rsquo;est-\u00e0-dire de pr\u00e9-interm\u00e9diaire \u00e0 avanc\u00e9.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-83041\" class=\"elementor-tab-title\" data-tab=\"41\" role=\"button\" aria-controls=\"elementor-tab-content-83041\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Que dira mon certificat de fin de stage ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-83041\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"41\" role=\"region\" aria-labelledby=\"elementor-tab-title-83041\"><p>Votre certificat de fin de cours indiquera le nombre d&rsquo;heures que vous avez \u00e9tudi\u00e9es dans notre \u00e9cole et indiquera que vous avez progress\u00e9 par rapport aux descripteurs du CECR \u00e0 un certain niveau du CECR.<\/p>\n<p>Sofia Rodrigo a suivi un cours d&rsquo;anglais pendant 40 heures et a progress\u00e9 au niveau interm\u00e9diaire sup\u00e9rieur (B2) selon les descripteurs du CECR.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-21b84d5c\" data-id=\"21b84d5c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d68226c cta-anchor elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d68226c\" data-element_type=\"section\" data-e-type=\"section\" id=\"cta-anchor\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64565624\" data-id=\"64565624\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-47292ae1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47292ae1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-22f2f144\" data-id=\"22f2f144\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46aba8e0 elementor-widget elementor-widget-global elementor-global-34549 elementor-global-20891 elementor-widget-html\" data-id=\"46aba8e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a id=\"cta\" class=\"cta\"\/>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-499f50a7\" data-id=\"499f50a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15dcceda elementor-section-stretched elementor-section-content-middle elementor-reverse-mobile cta3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15dcceda\" data-element_type=\"section\" data-e-type=\"section\" id=\"cta3\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;shape_divider_top&quot;:&quot;mountains&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-232901ce\" data-id=\"232901ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-597d5773 elementor-widget elementor-widget-global elementor-global-33384 elementor-global-20825 elementor-widget-heading\" data-id=\"597d5773\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Brochures et listes de prix<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23e8e3c0 elementor-section-stretched brochures elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23e8e3c0\" data-element_type=\"section\" data-e-type=\"section\" id=\"brochures\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;shape_divider_top&quot;:&quot;mountains&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bbb5cf2\" data-id=\"bbb5cf2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2bed6dc1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2bed6dc1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-51276e6e\" data-id=\"51276e6e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47d2e91d elementor-invisible elementor-widget elementor-widget-global elementor-global-33371 elementor-global-20831 elementor-widget-image\" data-id=\"47d2e91d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/online.fliphtml5.com\/fbxmh\/oaos\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1086\" src=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Irish-College-of-English-Junior-Summer-Camp-Brochure-2026-768x1086.jpg\" class=\"attachment-medium_large size-medium_large wp-image-29759\" alt=\"\" srcset=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Irish-College-of-English-Junior-Summer-Camp-Brochure-2026-768x1086.jpg 768w, https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Irish-College-of-English-Junior-Summer-Camp-Brochure-2026-212x300.jpg 212w, https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Irish-College-of-English-Junior-Summer-Camp-Brochure-2026-724x1024.jpg 724w, https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Irish-College-of-English-Junior-Summer-Camp-Brochure-2026-1086x1536.jpg 1086w, https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Irish-College-of-English-Junior-Summer-Camp-Brochure-2026.jpg 1414w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-61827cdf\" data-id=\"61827cdf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7734c9a2 e-transform elementor-invisible elementor-widget elementor-widget-global elementor-global-34907 elementor-global-20834 elementor-widget-image\" data-id=\"7734c9a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInRight&quot;,&quot;_transform_scaleX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/online.fliphtml5.com\/fbxmh\/koxb\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"596\" height=\"843\" src=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Courses-and-Fees-2026-1.png\" class=\"attachment-medium_large size-medium_large wp-image-30258\" alt=\"\" srcset=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Courses-and-Fees-2026-1.png 596w, https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Courses-and-Fees-2026-1-212x300.png 212w\" sizes=\"(max-width: 596px) 100vw, 596px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-21ecef35 elementor-align-center elementor-widget elementor-widget-global elementor-global-33380 elementor-global-20828 elementor-widget-button\" data-id=\"21ecef35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl elementor-animation-grow\" href=\"https:\/\/www.bookingiceireland.com\/\" target=\"_blank\" id=\"enroll\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">S'inscrire maintenant<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Abbaye de GlenstalProgramme r\u00e9sidentiel 2026 Limerick &#8211; Irlande28 juin &#8211; 2 ao\u00fbt11 &#8211; 17 ansAnglais et programme multi-activit\u00e9s L&rsquo;abbaye de Glenstal est l&rsquo;un des pensionnats les plus c\u00e9l\u00e8bres d&rsquo;Irlande. Les \u00e9tudiants qui participent \u00e0 notre camp d&rsquo;\u00e9t\u00e9 international pour jeunes \u00e0 Glenstal feront l&rsquo;exp\u00e9rience de la vie sur ce campus extraordinaire. Les \u00e9tudiants sont immerg\u00e9s [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":18968,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","footnotes":""},"class_list":["post-32355","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Camp d&#039;anglais r\u00e9sidentiel pour jeunes en Irlande - Inscriptions d\u00e8s maintenant pour juillet 2023<\/title>\n<meta name=\"description\" content=\"Une \u00e9cole d&#039;anglais prim\u00e9e propose un camp r\u00e9sidentiel dans la c\u00e9l\u00e8bre abbaye de Glenstal pour offrir un incroyable camp d&#039;anglais et d&#039;aventure dans cette \u00e9cole historique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iceireland.com\/fr\/camp-d-ete-anglais-irlande\/residential-english-camp-ireland\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Camp d&#039;anglais r\u00e9sidentiel pour jeunes en Irlande - Inscriptions d\u00e8s maintenant pour juillet 2023\" \/>\n<meta property=\"og:description\" content=\"Une \u00e9cole d&#039;anglais prim\u00e9e propose un camp r\u00e9sidentiel dans la c\u00e9l\u00e8bre abbaye de Glenstal pour offrir un incroyable camp d&#039;anglais et d&#039;aventure dans cette \u00e9cole historique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iceireland.com\/fr\/camp-d-ete-anglais-irlande\/residential-english-camp-ireland\/\" \/>\n<meta property=\"og:site_name\" content=\"Irish College of English\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-29T14:17:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Glenstal-Abbey-Overview.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/fr\\\/camp-d-ete-anglais-irlande\\\/residential-english-camp-ireland\\\/\",\"url\":\"https:\\\/\\\/www.iceireland.com\\\/fr\\\/camp-d-ete-anglais-irlande\\\/residential-english-camp-ireland\\\/\",\"name\":\"Camp d'anglais r\u00e9sidentiel pour jeunes en Irlande - Inscriptions d\u00e8s maintenant pour juillet 2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/fr\\\/camp-d-ete-anglais-irlande\\\/residential-english-camp-ireland\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/fr\\\/camp-d-ete-anglais-irlande\\\/residential-english-camp-ireland\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iceireland.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Glenstal-Abbey-Overview.png\",\"datePublished\":\"2023-08-08T10:30:33+00:00\",\"dateModified\":\"2026-04-29T14:17:13+00:00\",\"description\":\"Une \u00e9cole d'anglais prim\u00e9e propose un camp r\u00e9sidentiel dans la c\u00e9l\u00e8bre abbaye de Glenstal pour offrir un incroyable camp d'anglais et d'aventure dans cette \u00e9cole historique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/fr\\\/camp-d-ete-anglais-irlande\\\/residential-english-camp-ireland\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.iceireland.com\\\/fr\\\/camp-d-ete-anglais-irlande\\\/residential-english-camp-ireland\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/fr\\\/camp-d-ete-anglais-irlande\\\/residential-english-camp-ireland\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.iceireland.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Glenstal-Abbey-Overview.png\",\"contentUrl\":\"https:\\\/\\\/www.iceireland.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Glenstal-Abbey-Overview.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/fr\\\/camp-d-ete-anglais-irlande\\\/residential-english-camp-ireland\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.iceireland.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Camp d&rsquo;\u00e9t\u00e9 international d&rsquo;anglais junior Irlande\",\"item\":\"https:\\\/\\\/www.iceireland.com\\\/fr\\\/camp-d-ete-anglais-irlande\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Abbaye de Glenstal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.iceireland.com\\\/fr\\\/\",\"name\":\"Irish College of English\",\"description\":\"English School in Dublin, Malahide\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.iceireland.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/fr\\\/#organization\",\"name\":\"Irish College of English\",\"url\":\"https:\\\/\\\/www.iceireland.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.iceireland.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.iceireland.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/logo.png\",\"width\":593,\"height\":92,\"caption\":\"Irish College of English\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Camp d'anglais r\u00e9sidentiel pour jeunes en Irlande - Inscriptions d\u00e8s maintenant pour juillet 2023","description":"Une \u00e9cole d'anglais prim\u00e9e propose un camp r\u00e9sidentiel dans la c\u00e9l\u00e8bre abbaye de Glenstal pour offrir un incroyable camp d'anglais et d'aventure dans cette \u00e9cole historique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iceireland.com\/fr\/camp-d-ete-anglais-irlande\/residential-english-camp-ireland\/","og_locale":"fr_FR","og_type":"article","og_title":"Camp d'anglais r\u00e9sidentiel pour jeunes en Irlande - Inscriptions d\u00e8s maintenant pour juillet 2023","og_description":"Une \u00e9cole d'anglais prim\u00e9e propose un camp r\u00e9sidentiel dans la c\u00e9l\u00e8bre abbaye de Glenstal pour offrir un incroyable camp d'anglais et d'aventure dans cette \u00e9cole historique.","og_url":"https:\/\/www.iceireland.com\/fr\/camp-d-ete-anglais-irlande\/residential-english-camp-ireland\/","og_site_name":"Irish College of English","article_modified_time":"2026-04-29T14:17:13+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Glenstal-Abbey-Overview.png","type":"image\/png"}],"twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.iceireland.com\/fr\/camp-d-ete-anglais-irlande\/residential-english-camp-ireland\/","url":"https:\/\/www.iceireland.com\/fr\/camp-d-ete-anglais-irlande\/residential-english-camp-ireland\/","name":"Camp d'anglais r\u00e9sidentiel pour jeunes en Irlande - Inscriptions d\u00e8s maintenant pour juillet 2023","isPartOf":{"@id":"https:\/\/www.iceireland.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.iceireland.com\/fr\/camp-d-ete-anglais-irlande\/residential-english-camp-ireland\/#primaryimage"},"image":{"@id":"https:\/\/www.iceireland.com\/fr\/camp-d-ete-anglais-irlande\/residential-english-camp-ireland\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Glenstal-Abbey-Overview.png","datePublished":"2023-08-08T10:30:33+00:00","dateModified":"2026-04-29T14:17:13+00:00","description":"Une \u00e9cole d'anglais prim\u00e9e propose un camp r\u00e9sidentiel dans la c\u00e9l\u00e8bre abbaye de Glenstal pour offrir un incroyable camp d'anglais et d'aventure dans cette \u00e9cole historique.","breadcrumb":{"@id":"https:\/\/www.iceireland.com\/fr\/camp-d-ete-anglais-irlande\/residential-english-camp-ireland\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.iceireland.com\/fr\/camp-d-ete-anglais-irlande\/residential-english-camp-ireland\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.iceireland.com\/fr\/camp-d-ete-anglais-irlande\/residential-english-camp-ireland\/#primaryimage","url":"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Glenstal-Abbey-Overview.png","contentUrl":"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Glenstal-Abbey-Overview.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.iceireland.com\/fr\/camp-d-ete-anglais-irlande\/residential-english-camp-ireland\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.iceireland.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Camp d&rsquo;\u00e9t\u00e9 international d&rsquo;anglais junior Irlande","item":"https:\/\/www.iceireland.com\/fr\/camp-d-ete-anglais-irlande\/"},{"@type":"ListItem","position":3,"name":"Abbaye de Glenstal"}]},{"@type":"WebSite","@id":"https:\/\/www.iceireland.com\/fr\/#website","url":"https:\/\/www.iceireland.com\/fr\/","name":"Irish College of English","description":"English School in Dublin, Malahide","publisher":{"@id":"https:\/\/www.iceireland.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iceireland.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.iceireland.com\/fr\/#organization","name":"Irish College of English","url":"https:\/\/www.iceireland.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.iceireland.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.iceireland.com\/wp-content\/uploads\/2022\/03\/logo.png","contentUrl":"https:\/\/www.iceireland.com\/wp-content\/uploads\/2022\/03\/logo.png","width":593,"height":92,"caption":"Irish College of English"},"image":{"@id":"https:\/\/www.iceireland.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.iceireland.com\/fr\/wp-json\/wp\/v2\/pages\/32355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iceireland.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.iceireland.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.iceireland.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iceireland.com\/fr\/wp-json\/wp\/v2\/comments?post=32355"}],"version-history":[{"count":4,"href":"https:\/\/www.iceireland.com\/fr\/wp-json\/wp\/v2\/pages\/32355\/revisions"}],"predecessor-version":[{"id":36647,"href":"https:\/\/www.iceireland.com\/fr\/wp-json\/wp\/v2\/pages\/32355\/revisions\/36647"}],"up":[{"embeddable":true,"href":"https:\/\/www.iceireland.com\/fr\/wp-json\/wp\/v2\/pages\/18968"}],"wp:attachment":[{"href":"https:\/\/www.iceireland.com\/fr\/wp-json\/wp\/v2\/media?parent=32355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}