{"id":32131,"date":"2014-10-20T08:58:06","date_gmt":"2014-10-20T08:58:06","guid":{"rendered":"https:\/\/www.iceireland.com\/campo-estivo-inglese-irlanda\/english-summer-camp-dublin\/"},"modified":"2026-04-29T14:04:01","modified_gmt":"2026-04-29T14:04:01","slug":"english-summer-camp-dublin","status":"publish","type":"page","link":"https:\/\/www.iceireland.com\/it\/campo-estivo-inglese-irlanda\/english-summer-camp-dublin\/","title":{"rendered":"Campi estivi di inglese classico in Irlanda"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"32131\" class=\"elementor elementor-32131 elementor-78\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d1a2909 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d1a2909\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dbaa726\" data-id=\"dbaa726\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30575b8 elementor-widget elementor-widget-heading\" data-id=\"30575b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>Programma Classic Junior 2026  <\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0d38c73 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0d38c73\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-531cfcd\" data-id=\"531cfcd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d86501 elementor-widget elementor-widget-heading\" data-id=\"0d86501\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Dublino - Irlanda,<br>15 giugno - 23 agosto<br>11 - 17 anni<br>Programma di soggiorno in casa in inglese e multiattivit\u00e0<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b6626e9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b6626e9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0ea05d6\" data-id=\"0ea05d6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80167de elementor-widget elementor-widget-text-editor\" data-id=\"80167de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Il nostro Programma Classico \u00e8 il nostro fiore all&#8217;occhiello tra i campi estivi di inglese e attira il maggior numero di studenti. Si basa su una solida base accademica e la progressione \u00e8 il nostro obiettivo.  Le lezioni si tengono ogni mattina dal luned\u00ec al venerd\u00ec. Ogni corso \u00e8 supportato da un programma attentamente studiato e un libro di testo. Le lezioni si focalizzano nello sviluppo delle abilit\u00e0 linguistiche principali, con particolare enfasi a quelle di ascolto e orali. Inoltre, le nostre attivit\u00e0 sono studiate su misura per mantenere gli studenti attivi e divertiti mentre vedono il meglio di Dublino e delle regioni circostanti.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10d6d50 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10d6d50\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b75e215\" data-id=\"b75e215\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f5f289 elementor-widget elementor-widget-video\" data-id=\"5f5f289\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;autoplay&quot;:&quot;yes&quot;,&quot;play_on_mobile&quot;:&quot;yes&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"autoplay\" title=\"vimeo Video Player\" src=\"https:\/\/player.vimeo.com\/video\/229578629?autoplay=1&amp;playsinline=1&amp;color&amp;autopause=0&amp;loop=1&amp;muted=1&amp;title=1&amp;portrait=1&amp;byline=1#t=\"><\/iframe>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8595140 elementor-widget elementor-widget-spacer\" data-id=\"8595140\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3251cca elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3251cca\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-bb86b22\" data-id=\"bb86b22\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a9665a0 elementor-widget elementor-widget-text-editor\" data-id=\"a9665a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span style=\"color: #ffffff;\"><strong>Scuola pluripremiata<\/strong><\/span><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2c9924e\" data-id=\"2c9924e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88540e4 elementor-widget elementor-widget-text-editor\" data-id=\"88540e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><b>Soggiorni in casa nel raggio di 4 km<\/b><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-af2c4df\" data-id=\"af2c4df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca35f1d elementor-widget elementor-widget-text-editor\" data-id=\"ca35f1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span style=\"color: #ffffff;\"><strong>Una sola nazionalit\u00e0 per famiglia<\/strong><\/span><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a2d9f94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a2d9f94\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e376a0\" data-id=\"2e376a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37309b7 elementor-widget elementor-widget-spacer\" data-id=\"37309b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8782493 elementor-widget elementor-widget-heading\" data-id=\"8782493\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>\u2018Citt\u00e0 sul mare a Dublino\u2019<\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45105dd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45105dd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-90aed68\" data-id=\"90aed68\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd4b0cd elementor-widget elementor-widget-heading\" data-id=\"bd4b0cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Scopri il meglio di Dublino e dell'Irlanda<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-beb9e01 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"beb9e01\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4786def\" data-id=\"4786def\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c41bae7 elementor-widget elementor-widget-text-editor\" data-id=\"c41bae7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">La nostra scuola si trova a Malahide, una bella cittadina ricca sulla costa di Dublino. Malahide \u00e8 una scelta ideale per ogni alloggio a Dublino .  <strong>Malahide \u00e8 a soli 22 minuti di Dart dal centro di Dublino e a soli 10 minuti dall&#8217;aeroporto.<\/strong>  La nostra scuola offre agli studenti l&#8217;opportunit\u00e0 di sperimentare il meglio di Dublino vivendo in alloggi a pochi passi o a un brevissimo viaggio in autobus. Malahide \u00e8 una delle mete pi\u00f9 ambite di Dublino per viverci. Abbiamo ricevuto la nomina di &#8216;Miglior posto dove vivere in Irlanda 2021&#8217;, ed \u00e8 anche meta molto amata dagli studenti e dai turisti. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c657ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c657ae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2cb11cb\" data-id=\"2cb11cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3da8b1e elementor-widget elementor-widget-video\" data-id=\"3da8b1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;play_on_mobile&quot;:&quot;yes&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"autoplay\" title=\"vimeo Video Player\" src=\"https:\/\/player.vimeo.com\/video\/636495304?autoplay=1&amp;playsinline=1&amp;color&amp;autopause=0&amp;dnt=true&amp;loop=1&amp;muted=1&amp;title=0&amp;portrait=0&amp;byline=0#t=\"><\/iframe>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5821d34 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5821d34\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-113b5ef\" data-id=\"113b5ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85b6f46 elementor-widget elementor-widget-gallery\" data-id=\"85b6f46\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;justified&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;ideal_row_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:200,&quot;sizes&quot;:[]},&quot;ideal_row_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:150,&quot;sizes&quot;:[]},&quot;ideal_row_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:150,&quot;sizes&quot;:[]},&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Host-Family-e1756197699586.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"85b6f46\" data-elementor-lightbox-title=\"ICE Host Family\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzAzODcsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9JQ0UtSG9zdC1GYW1pbHktZTE3NTYxOTc2OTk1ODYucG5nIiwic2xpZGVzaG93IjoiODViNmY0NiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Host-Family-e1756197699586.png\" data-width=\"1414\" data-height=\"2000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Malahide-Village-e1756197844900.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"85b6f46\" data-elementor-lightbox-title=\"ICE Malahide Village\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzAzOTYsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9JQ0UtTWFsYWhpZGUtVmlsbGFnZS1lMTc1NjE5Nzg0NDkwMC5wbmciLCJzbGlkZXNob3ciOiI4NWI2ZjQ2In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Malahide-Village-e1756197844900.png\" data-width=\"1414\" data-height=\"2000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Malahide-Village-2-e1756198039286.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"85b6f46\" data-elementor-lightbox-title=\"ICE Malahide Village (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzA0MDQsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9JQ0UtTWFsYWhpZGUtVmlsbGFnZS0yLWUxNzU2MTk4MDM5Mjg2LnBuZyIsInNsaWRlc2hvdyI6Ijg1YjZmNDYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Malahide-Village-2-e1756198039286.png\" data-width=\"1414\" data-height=\"2000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Malahide-Village-3-e1756198172150.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"85b6f46\" data-elementor-lightbox-title=\"ICE Malahide Village (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzA0MTIsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9JQ0UtTWFsYWhpZGUtVmlsbGFnZS0zLWUxNzU2MTk4MTcyMTUwLnBuZyIsInNsaWRlc2hvdyI6Ijg1YjZmNDYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Malahide-Village-3-e1756198172150.png\" data-width=\"1414\" data-height=\"2000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Malahide-Village-4-e1756198366784.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"85b6f46\" data-elementor-lightbox-title=\"ICE Malahide Village (4)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzA0MjAsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9JQ0UtTWFsYWhpZGUtVmlsbGFnZS00LWUxNzU2MTk4MzY2Nzg0LnBuZyIsInNsaWRlc2hvdyI6Ijg1YjZmNDYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Malahide-Village-4-e1756198366784.png\" data-width=\"1414\" data-height=\"2000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-14-e1756210667793.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"85b6f46\" data-elementor-lightbox-title=\"ICE Summer Camp 2026 Banner Photos (14)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzA1MTMsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9JQ0UtU3VtbWVyLUNhbXAtMjAyNi1CYW5uZXItUGhvdG9zLTE0LWUxNzU2MjEwNjY3NzkzLnBuZyIsInNsaWRlc2hvdyI6Ijg1YjZmNDYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-14-e1756210667793.png\" data-width=\"1500\" data-height=\"1000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56df06a elementor-widget elementor-widget-spacer\" data-id=\"56df06a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4435f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d4435f1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eca3bc7\" data-id=\"eca3bc7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5131f81 elementor-widget elementor-widget-heading\" data-id=\"5131f81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Panoramica del programma Classic<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-399ebc7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"399ebc7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e107e2d\" data-id=\"e107e2d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5485a19 elementor-widget elementor-widget-image\" data-id=\"5485a19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1500\" height=\"1000\" src=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-21.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-30677\" alt=\"\" srcset=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-21.png 1500w, https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-21-300x200.png 300w, https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-21-1024x683.png 1024w, https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-21-768x512.png 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-624bb4f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"624bb4f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-69ec7eb\" data-id=\"69ec7eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef75e41 elementor-widget elementor-widget-gallery\" data-id=\"ef75e41\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;justified&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;ideal_row_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:200,&quot;sizes&quot;:[]},&quot;ideal_row_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:150,&quot;sizes&quot;:[]},&quot;ideal_row_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:150,&quot;sizes&quot;:[]},&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-16-e1756211184514.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ef75e41\" data-elementor-lightbox-title=\"ICE Summer Camp 2026 Banner Photos (16)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzA1MzAsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9JQ0UtU3VtbWVyLUNhbXAtMjAyNi1CYW5uZXItUGhvdG9zLTE2LWUxNzU2MjExMTg0NTE0LnBuZyIsInNsaWRlc2hvdyI6ImVmNzVlNDEifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-16-e1756211184514.png\" data-width=\"1500\" data-height=\"1000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-15-e1756210938945.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ef75e41\" data-elementor-lightbox-title=\"ICE Summer Camp 2026 Banner Photos (15)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzA1MjIsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9JQ0UtU3VtbWVyLUNhbXAtMjAyNi1CYW5uZXItUGhvdG9zLTE1LWUxNzU2MjEwOTM4OTQ1LnBuZyIsInNsaWRlc2hvdyI6ImVmNzVlNDEifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-15-e1756210938945.png\" data-width=\"1500\" data-height=\"1000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-17-e1756211439850.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ef75e41\" data-elementor-lightbox-title=\"ICE Summer Camp 2026 Banner Photos (17)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzA1NDEsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9JQ0UtU3VtbWVyLUNhbXAtMjAyNi1CYW5uZXItUGhvdG9zLTE3LWUxNzU2MjExNDM5ODUwLnBuZyIsInNsaWRlc2hvdyI6ImVmNzVlNDEifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-17-e1756211439850.png\" data-width=\"1500\" data-height=\"1000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-18-e1756211512508.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ef75e41\" data-elementor-lightbox-title=\"ICE Summer Camp 2026 Banner Photos (18)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzA1NTAsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9JQ0UtU3VtbWVyLUNhbXAtMjAyNi1CYW5uZXItUGhvdG9zLTE4LWUxNzU2MjExNTEyNTA4LnBuZyIsInNsaWRlc2hvdyI6ImVmNzVlNDEifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-18-e1756211512508.png\" data-width=\"1500\" data-height=\"1000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-19-e1756211638190.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ef75e41\" data-elementor-lightbox-title=\"ICE Summer Camp 2026 Banner Photos (19)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzA1NTgsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9JQ0UtU3VtbWVyLUNhbXAtMjAyNi1CYW5uZXItUGhvdG9zLTE5LWUxNzU2MjExNjM4MTkwLnBuZyIsInNsaWRlc2hvdyI6ImVmNzVlNDEifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-19-e1756211638190.png\" data-width=\"1500\" data-height=\"1000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-ICE-Summer-Camp-Brochure-2025.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ef75e41\" data-elementor-lightbox-title=\"Copy of ICE Summer Camp Brochure 2025\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzA1NjYsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9Db3B5LW9mLUlDRS1TdW1tZXItQ2FtcC1Ccm9jaHVyZS0yMDI1LnBuZyIsInNsaWRlc2hvdyI6ImVmNzVlNDEifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-ICE-Summer-Camp-Brochure-2025.png\" data-width=\"1414\" data-height=\"2000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-ICE-Summer-Camp-Brochure-2025-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ef75e41\" data-elementor-lightbox-title=\"Copy of ICE Summer Camp Brochure 2025 (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzA1NzQsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9Db3B5LW9mLUlDRS1TdW1tZXItQ2FtcC1Ccm9jaHVyZS0yMDI1LTEucG5nIiwic2xpZGVzaG93IjoiZWY3NWU0MSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-ICE-Summer-Camp-Brochure-2025-1.png\" data-width=\"1414\" data-height=\"2000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-20.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ef75e41\" data-elementor-lightbox-title=\"ICE Summer Camp 2026 Banner Photos (20)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzA1ODIsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9JQ0UtU3VtbWVyLUNhbXAtMjAyNi1CYW5uZXItUGhvdG9zLTIwLnBuZyIsInNsaWRlc2hvdyI6ImVmNzVlNDEifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-20.png\" data-width=\"1500\" data-height=\"1000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-ICE-Summer-Camp-Brochure-2025-2-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ef75e41\" data-elementor-lightbox-title=\"Copy of ICE Summer Camp Brochure 2025 (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzA1OTgsInVybCI6Imh0dHBzOlwvXC93d3cuaWNlaXJlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9Db3B5LW9mLUlDRS1TdW1tZXItQ2FtcC1Ccm9jaHVyZS0yMDI1LTItMS5wbmciLCJzbGlkZXNob3ciOiJlZjc1ZTQxIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Copy-of-ICE-Summer-Camp-Brochure-2025-2-1.png\" data-width=\"1414\" data-height=\"2000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48fefec elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"48fefec\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2634222\" data-id=\"2634222\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22e9143 elementor-widget elementor-widget-spacer\" data-id=\"22e9143\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-318a2b3 elementor-widget elementor-widget-heading\" data-id=\"318a2b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Esempio di programma di 2 settimane<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cea9d16 elementor-widget elementor-widget-image\" data-id=\"cea9d16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Classic-Sample-Programme-2026-e1756135507517.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c4e9bf7 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c4e9bf7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;shape_divider_top&quot;:&quot;mountains&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-693fb9f1\" data-id=\"693fb9f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-140dae60 elementor-widget elementor-widget-global elementor-global-34721 elementor-global-20855 elementor-widget-heading\" data-id=\"140dae60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cosa \u00e8 incluso<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e1bc462 elementor-widget__width-initial elementor-widget elementor-widget-global elementor-global-34712 elementor-global-20858 elementor-widget-text-editor\" data-id=\"3e1bc462\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"font-size: 26px; font-weight: bold;\">All Inclusive<\/span><\/p><p style=\"text-align: center;\">Crediamo nell&#8217;offerta di un prezzo del corso all inclusive. Tutto \u00e8 incluso, non ci sono costi aggiuntivi per la registrazione della valutazione o per l&#8217;amministrazione. Tutte le attivit\u00e0, i pass per il viaggio, i biglietti d&#8217;ingresso e i pasti sono inclusi.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d9b623f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d9b623f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-735f3610\" data-id=\"735f3610\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-203a3313 elementor-position-inline-start elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-global elementor-global-34624 elementor-global-20876 elementor-widget-icon-box\" data-id=\"203a3313\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-grow\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tClassi\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d1f8761 elementor-widget elementor-widget-text-editor\" data-id=\"7d1f8761\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Lezioni:<\/strong><\/p><p>Abbiamo un programma Junior appositamente studiato per incoraggiare la progressione e la fiducia di tuo figlio. Crediamo nell&#8217;uso di materiale autentico per accrescere l&#8217;amore per la lingua. Le classi sono internazionali.<\/p><ul><li>Orario: 15 ore di lezione a settimana e l&#8217;uso del libro di testo \u00e8 incluso.<\/li><li>Orari: Dalle 8.45 alle 12 ogni giorno della settimana con una pausa di 15 minuti.<span style=\"font-weight: bold;\"> <\/span><\/li><li>Dimensione massima della classe:<span style=\"font-weight: bold;\"> <span style=\"font-weight: 400;\">15 studenti.<\/span><br><\/span><\/li><li>Livelli di ingresso: Tutti i livelli da pre-intermedio ad avanzato, da A2 a C1 della scala CEFR.<\/li><\/ul><p><strong>Programma interculturale per adolescenti irlandesi<\/strong><\/p><p>Nell&#8217;ambito dei nostri continui sforzi per mantenere alta la qualit\u00e0 delle lezioni e per migliorare l&#8217;esperienza interculturale dei nostri studenti, abbiamo organizzato delle lezioni settimanali chiamate &#8220;Intercultural Teenage Programme&#8221;. Gli studenti irlandesi adolescenti si uniscono alle lezioni per condurre un&#8217;esercitazione a fianco dell&#8217;insegnante, dando ai nostri studenti l&#8217;opportunit\u00e0 di entrare in contatto con adolescenti irlandesi, loro coetanei. <\/p><p><b>Rapporto e certificato dello studente<\/b><\/p><p>Alla fine del corso, gli studenti ricevono un certificato di frequenza e di partecipazione e una relazione dell&#8217;insegnante sui loro progressi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3ac794cd\" data-id=\"3ac794cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-630af227 elementor-position-inline-start elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-global elementor-global-34618 elementor-global-20879 elementor-widget-icon-box\" data-id=\"630af227\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-grow\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSistemazione\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c1fbe7c elementor-widget elementor-widget-text-editor\" data-id=\"4c1fbe7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Alloggio &#8211; Famiglia<\/strong><\/p><p>Tutti i nostri alloggi si trovano in famiglie a Malahide, a pochi passi dalla scuola, o in zone limitrofe con un brevissimo viaggio in autobus. In genere i nostri ospiti accolgono 2-3 studenti alla volta. Le famiglie faranno il bucato degli studenti come parte della loro normale routine domestica. Abbiniamo con cura gli studenti alle famiglie.<\/p><p><b>Pasti<\/b><\/p><p>Le famiglie provvedono alla colazione, al pranzo al sacco e al pasto serale. I pasti sono nutrienti e su richiesta possiamo soddisfare alcune diete speciali. <\/p><p><b>Pacchetto di benvenuto<\/b><\/p><p>All&#8217;arrivo, inoltre, diamo agli studenti un pacchetto di benvenuto che include una bottiglia d&#8217;acqua riutilizzabile e la nostra scuola ha una stazione di rifornimento dell&#8217;acqua.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5ee3eb7b\" data-id=\"5ee3eb7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-456a65f9 elementor-position-inline-start elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-global elementor-global-34588 elementor-global-20882 elementor-widget-icon-box\" data-id=\"456a65f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-grow\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAttivit\u00e0\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77074b7b elementor-widget elementor-widget-text-editor\" data-id=\"77074b7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Attivit\u00e0 nei giorni feriali<\/b><\/p><p>Gli studenti hanno un programma completo dalle 8.45 alle 17.00 ogni giorno dal luned\u00ec al venerd\u00ec. Lezioni al mattino e attivit\u00e0 e visite guidate nel pomeriggio\/sera. <\/p>\n<p>Gli studenti sono accompagnati da un esperto ICE Leader durante tutte le attivit\u00e0. I nostri studenti si recano nel centro di Dublino almeno due volte a settimana e hanno un programma divertente e coinvolgente che prevede visite guidate, sport, spettacoli e attivit\u00e0 ricreative.<\/p>\n<p><b>Attivit\u00e0 serali<\/b><\/p>\n<p>Due sere a settimana gli studenti possono partecipare alle nostre serate disco facoltative senza costi aggiuntivi.<\/p>\n<p><b>Gite di un giorno intero<\/b><\/p><p>Ogni sabato i nostri studenti fanno una gita di un&#8217;intera giornata accompagnati da un ICE Leader per vedere il meglio delle aree circostanti. Esempi di gite giornaliere: Glendalough, Kilkenny, Belfast, Zoo di Dublino. <\/p>\n<p><b>Pass di viaggio<\/b><\/p>\n<p>Gli studenti ricevono un Dublin Travel Pass per trasporti pubblici illimitati per tutta la durata del loro soggiorno; gli studenti utilizzano il travel pass per il programma di attivit\u00e0 a Dublino e per gli spostamenti necessari da e per la scuola.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25b72c90 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"25b72c90\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0c62ed2\" data-id=\"0c62ed2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7794d105 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7794d105\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5074daaa\" data-id=\"5074daaa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1625a396 elementor-widget elementor-widget-global elementor-global-34572 elementor-global-20888 elementor-widget-heading\" data-id=\"1625a396\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Domande frequenti<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f641650 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f641650\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-15614e\" data-id=\"15614e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-51183f64\" data-id=\"51183f64\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-324d5fed elementor-widget elementor-widget-toggle\" data-id=\"324d5fed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8431\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8431\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quali saranno gli orari?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8431\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8431\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Una giornata tipica: Gli studenti vengono svegliati da chi li ospita, fanno una doccia e fanno colazione. Gli studenti ricevono un pranzo al sacco per la giornata. Gli studenti vanno a scuola a piedi o prendono l&#8217;autobus utilizzando il Dublin Travel Pass. Gli studenti tornano a casa verso le 18:00 dopo il programma di lezioni e attivit\u00e0. Al ritorno a casa, gli studenti cenano con la famiglia ospitante e chiacchierano della loro giornata. Gli studenti possono trascorrere la serata rilassandosi con la famiglia o con gli amici oppure partecipare a un&#8217;attivit\u00e0 serale organizzata (2 sere a settimana). Il coprifuoco \u00e8 fissato alle 21.30, orario in cui tutti gli studenti devono rientrare a casa durante i nostri campi estivi di inglese. Gli studenti e le famiglie hanno accesso 24 ore su 24 a un numero di telefono per le emergenze e un membro del nostro team \u00e8 sempre pronto ad aiutarli.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8432\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-8432\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Qual \u00e8 il mix di nazionalit\u00e0?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8432\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-8432\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">In genere nella nostra scuola sono rappresentate tra le 15 e le 27 nazionalit\u00e0.<\/p>\n<p>Per saperne di pi\u00f9 sul <a href=\"https:\/\/www.iceireland.com\/it\/nationality-mix\/\">Mix di nazionalit\u00e0<\/a>.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8433\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-8433\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ci sono costi aggiuntivi o supplementari e di quanta paghetta ha bisogno uno studente?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8433\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-8433\"><div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Il programma \u00e8 tutto compreso, senza costi aggiuntivi. La maggior parte degli studenti porta con s\u00e9 tra gli 80 e i 100 euro di paghetta a settimana per souvenir, dolci, ecc. <\/p>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8434\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-8434\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Come faccio a scegliere le date e gli orari di arrivo e partenza?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8434\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-8434\"><div class=\"hidden-content\">\n<p>Un soggiorno di 2 settimane prevede 14 notti di alloggio, 3 settimane 21 notti e 4 settimane 28 notti. La maggior parte degli studenti arriva il sabato o la domenica e parte il sabato o la domenica corrispondenti, ma pu\u00f2 arrivare in qualsiasi giorno della settimana e partire il giorno corrispondente, ad esempio da gioved\u00ec a gioved\u00ec. <\/p>\n<p>Offriamo un servizio di trasferimento aeroportuale &#8220;meet and greet&#8221;. Possiamo organizzare i trasferimenti aeroportuali per l&#8217;arrivo\/la partenza in qualsiasi momento.  <\/p>\n<p>Inoltre, possiamo collaborare con i servizi delle compagnie aeree UM e compilare i moduli di indennit\u00e0 di partenza se richiesti da alcune compagnie aeree per gli studenti che viaggiano da soli.<\/p>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8435\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-8435\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quanti studenti ci saranno in una classe?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8435\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-8435\"><div class=\"hidden-content\">\n<p class=\"hiddenContentp\">C&#8217;\u00e8 un massimo di 15 studenti per classe, con una media di 13 studenti per classe.<\/p>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8436\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-8436\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quali qualifiche hanno i tuoi insegnanti?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8436\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-8436\"><div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Tutti i nostri insegnanti sono in possesso di una laurea e di un&#8217;ulteriore qualifica per l&#8217;insegnamento dell&#8217;inglese e tutti i nostri insegnanti sono riconosciuti come insegnanti di lingua inglese qualificati dall&#8217;ACELS.<\/p>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8437\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-8437\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Come si fa a collocare gli studenti nel loro corretto livello di inglese?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8437\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-8437\"><div class=\"hidden-content\">\n<p>Eseguiamo un test agli studenti prima dell&#8217;arrivo e il primo giorno l&#8217;insegnante verifica se sono nel livello corretto.<\/p>\n<p>Monitoriamo i progressi degli studenti con test settimanali.<\/p>\n<p>Gli studenti possono spostarsi di livello se riteniamo che non siano nel livello corretto.<\/p>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8438\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-8438\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quanti livelli di inglese hai?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8438\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-8438\"><div class=\"hidden-content\">\n<p>Tutti i nostri programmi junior sono allineati al QCER (Quadro Comune Europeo di Riferimento). Offriamo livelli da A2 a C1, per studenti di livello pre-intermedio o avanzato. <\/p>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8439\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-8439\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Qual \u00e8 il coprifuoco?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8439\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-8439\"><div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Si applica un severo coprifuoco alle 21.30.<\/p>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84310\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-84310\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Hai un numero di emergenza e un aiuto disponibile?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84310\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-84310\"><div class=\"hidden-content\">\n<p class=\"hiddenContentp\">S\u00ec, offriamo un numero di emergenza attivo 24 ore su 24 e siamo sempre disponibili ad aiutarti.<\/p>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84311\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-84311\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Cosa succede il primo giorno di scuola?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84311\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-84311\"><div class=\"hidden-content\">\n<p class=\"hiddenContentp\">I padroni di casa accompagneranno gli studenti a scuola. All&#8217;arrivo, gli studenti riceveranno un pacchetto di benvenuto con informazioni e saranno accompagnati nella classe del loro livello. <\/p>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84312\" class=\"elementor-tab-title\" data-tab=\"12\" role=\"button\" aria-controls=\"elementor-tab-content-84312\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Puoi fornire una lettera di invito ai fini del visto?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84312\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"12\" role=\"region\" aria-labelledby=\"elementor-tab-title-84312\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">S\u00ec, forniamo lettere per tutti gli studenti provenienti da paesi extra UE che hanno bisogno di un visto per entrare in Irlanda.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84313\" class=\"elementor-tab-title\" data-tab=\"13\" role=\"button\" aria-controls=\"elementor-tab-content-84313\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">C'\u00e8 il wifi gratuito nella scuola e nella casa di soggiorno?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84313\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"13\" role=\"region\" aria-labelledby=\"elementor-tab-title-84313\"><p>S\u00ec<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84314\" class=\"elementor-tab-title\" data-tab=\"14\" role=\"button\" aria-controls=\"elementor-tab-content-84314\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quando devo pagare le tasse?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84314\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"14\" role=\"region\" aria-labelledby=\"elementor-tab-title-84314\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Al momento della prenotazione viene versato un deposito di 200 euro. Il resto della quota deve essere pagato 4 settimane prima dell&#8217;arrivo. <\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84315\" class=\"elementor-tab-title\" data-tab=\"15\" role=\"button\" aria-controls=\"elementor-tab-content-84315\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Qual \u00e8 la politica di rimborso?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84315\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"15\" role=\"region\" aria-labelledby=\"elementor-tab-title-84315\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<ol>\n<li>Politica di cancellazione e rimborso:\n<p>La nostra garanzia &#8220;Prenota con fiducia&#8221; \u00e8 stata pensata per offrire flessibilit\u00e0 e allo stesso tempo per garantire il miglior servizio a tutti gli studenti. Consigliamo vivamente agli studenti\/genitori\/tutori\/organizzatori del gruppo di acquistare un&#8217;assicurazione di viaggio per tutelarsi da eventuali cambiamenti imprevisti nei loro piani di viaggio.  <\/p>\n<p>Cancellazione 7 giorni o pi\u00f9 prima dell&#8217;arrivo &#8211; Rimborso totale<\/p>\n<p>Cancellazione da 3 a 6 giorni prima dell&#8217;arrivo: rimborso del 50% dell&#8217;importo totale della prenotazione.<\/p>\n<p>Cancellazione 1 &#8211; 2 giorni prima dell&#8217;arrivo &#8211; Nessun rimborso<\/p>\n<p><strong>Note importanti:<\/strong><\/p>\n<p>Tutte le cancellazioni devono essere effettuate per iscritto all&#8217;indirizzo <a href=\"mailto:info@iceireland.com\">info@iceireland.com<\/a> e devono essere accettate dal Collegio.<\/p>\n<ul>\n<li>I rimborsi saranno elaborati entro 7-10 giorni lavorativi dalla conferma della cancellazione.<\/li>\n<li>Non \u00e8 previsto alcun rimborso in caso di mancata presentazione o di partenza anticipata dai corsi.<\/li>\n<li>Ai fini della nostra politica di rimborso, l&#8217;arrivo \u00e8 previsto per le ore 10 del giorno di arrivo, indipendentemente dall&#8217;orario di arrivo effettivo.<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84316\" class=\"elementor-tab-title\" data-tab=\"16\" role=\"button\" aria-controls=\"elementor-tab-content-84316\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">La lavanderia di mio figlio viene fatta per lui?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84316\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"16\" role=\"region\" aria-labelledby=\"elementor-tab-title-84316\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">S\u00ec, in genere una volta alla settimana da parte dell&#8217;ospitante.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84317\" class=\"elementor-tab-title\" data-tab=\"17\" role=\"button\" aria-controls=\"elementor-tab-content-84317\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ricever\u00f2 una lista di imballaggio?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84317\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"17\" role=\"region\" aria-labelledby=\"elementor-tab-title-84317\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">S\u00ec, riceverai una lista di imballaggio all&#8217;interno del manuale dello studente prima dell&#8217;arrivo.<\/p>\n<\/div>\n<\/div>\n<div class=\"exp-col-content-holder\"> <\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84318\" class=\"elementor-tab-title\" data-tab=\"18\" role=\"button\" aria-controls=\"elementor-tab-content-84318\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Mio figlio pu\u00f2 andare da solo nel centro di Dublino?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84318\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"18\" role=\"region\" aria-labelledby=\"elementor-tab-title-84318\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">No, gli studenti non possono lasciare Malahide\/Portmarnock o il loro quartiere senza il consenso scritto dei genitori e consigliamo ai genitori di non incoraggiare gli studenti a recarsi a Dublino da soli.<\/p>\n<\/div>\n<\/div>\n<div class=\"exp-col-content-holder\"> <\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84319\" class=\"elementor-tab-title\" data-tab=\"19\" role=\"button\" aria-controls=\"elementor-tab-content-84319\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Il prezzo include i voli?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84319\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"19\" role=\"region\" aria-labelledby=\"elementor-tab-title-84319\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">No, dovrai prenotare i tuoi voli da solo.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84320\" class=\"elementor-tab-title\" data-tab=\"20\" role=\"button\" aria-controls=\"elementor-tab-content-84320\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">La maggior parte degli studenti viene in gruppo o si reca all'ICE come singolo?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84320\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"20\" role=\"region\" aria-labelledby=\"elementor-tab-title-84320\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Circa il 40% dei nostri studenti \u00e8 costituito da singoli e il resto da gruppi organizzati. I singoli si ritrovano tutti insieme per le attivit\u00e0 pomeridiane e sono divisi per et\u00e0, quindi \u00e8 facile fare nuove amicizie. <\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"exp-col-content-holder\"> <\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84321\" class=\"elementor-tab-title\" data-tab=\"21\" role=\"button\" aria-controls=\"elementor-tab-content-84321\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Accetterai un bambino di 10 anni o un ragazzo di 18 anni?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84321\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"21\" role=\"region\" aria-labelledby=\"elementor-tab-title-84321\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p>No, la nostra fascia di et\u00e0 va dagli 11 ai 17 anni. Tuttavia, in determinate circostanze, se un ragazzo compie 18 anni e frequenta ancora la scuola superiore fino all&#8217;estate del campo, possiamo accettarlo nel programma. <\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84322\" class=\"elementor-tab-title\" data-tab=\"22\" role=\"button\" aria-controls=\"elementor-tab-content-84322\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ricever\u00f2 un pacchetto informativo prima dell'arrivo?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84322\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"22\" role=\"region\" aria-labelledby=\"elementor-tab-title-84322\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">S\u00ec, tutti gli studenti e i genitori ricevono un manuale e una lista dei bagagli prima dell&#8217;arrivo.<\/p>\n<\/div>\n<\/div>\n<div class=\"exp-col-content-holder\"> <\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84323\" class=\"elementor-tab-title\" data-tab=\"23\" role=\"button\" aria-controls=\"elementor-tab-content-84323\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quando ricever\u00f2 le informazioni sulla famiglia ospitante e quali saranno?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84323\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"23\" role=\"region\" aria-labelledby=\"elementor-tab-title-84323\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Riceverai il profilo della tua famiglia ospitante con una mappa della sua posizione 3 settimane prima dell&#8217;arrivo.<\/p>\n<\/div>\n<\/div>\n<div class=\"exp-col-content-holder\"> <\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84324\" class=\"elementor-tab-title\" data-tab=\"24\" role=\"button\" aria-controls=\"elementor-tab-content-84324\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Posso contattare la famiglia prima dell'arrivo?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84324\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"24\" role=\"region\" aria-labelledby=\"elementor-tab-title-84324\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">S\u00ec, il loro indirizzo e-mail sar\u00e0 presente nel loro profilo.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84325\" class=\"elementor-tab-title\" data-tab=\"25\" role=\"button\" aria-controls=\"elementor-tab-content-84325\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Cosa succede se mio figlio non \u00e8 soddisfatto della famiglia ospitante, della classe o di qualsiasi aspetto del suo soggiorno?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84325\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"25\" role=\"region\" aria-labelledby=\"elementor-tab-title-84325\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Siamo sempre pronti ad aiutare e a trasferire un bambino in una nuova famiglia o in una nuova classe e ad assisterlo in ogni modo possibile per far s\u00ec che sia felice.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84326\" class=\"elementor-tab-title\" data-tab=\"26\" role=\"button\" aria-controls=\"elementor-tab-content-84326\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Mio figlio avr\u00e0 momenti di non supervisione?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84326\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"26\" role=\"region\" aria-labelledby=\"elementor-tab-title-84326\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">S\u00ec, nei nostri programmi in famiglia gli studenti spesso non sono sorvegliati, ad esempio per andare e tornare da scuola, la sera, durante il tempo libero, ecc.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84327\" class=\"elementor-tab-title\" data-tab=\"27\" role=\"button\" aria-controls=\"elementor-tab-content-84327\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Come funziona il trasferimento aeroportuale per mio figlio?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84327\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"27\" role=\"region\" aria-labelledby=\"elementor-tab-title-84327\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Facciamo in modo che un membro del nostro staff attenda il tuo bambino all&#8217;aeroporto con un cartello. Ci assicuriamo inoltre di avere il numero di cellulare di tuo figlio e di avere il numero del nostro autista e anche il nostro numero di emergenza in caso di ritardo, ecc. <\/p>\n<\/div>\n<\/div>\n<div class=\"exp-col-content-holder\"> <\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84328\" class=\"elementor-tab-title\" data-tab=\"28\" role=\"button\" aria-controls=\"elementor-tab-content-84328\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Aiuterete mio figlio a fare il check-in in aeroporto?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84328\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"28\" role=\"region\" aria-labelledby=\"elementor-tab-title-84328\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">S\u00ec, basta chiedere aiuto alla partenza e il nostro autista aiuter\u00e0 il bambino a fare il check-in e lo porter\u00e0 fino ai controlli di sicurezza, se lo desideri, senza alcun costo aggiuntivo.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84329\" class=\"elementor-tab-title\" data-tab=\"29\" role=\"button\" aria-controls=\"elementor-tab-content-84329\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Potete registrare mio figlio alla partenza con un servizio per minori non accompagnati o compilare il modulo di indennit\u00e0 per Aerlingus, c'\u00e8 un costo aggiuntivo?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84329\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"29\" role=\"region\" aria-labelledby=\"elementor-tab-title-84329\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">S\u00ec, siamo lieti di effettuare qualsiasi iscrizione senza alcun costo aggiuntivo.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84330\" class=\"elementor-tab-title\" data-tab=\"30\" role=\"button\" aria-controls=\"elementor-tab-content-84330\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Come scegliete e garantite la qualit\u00e0 dei vostri alloggi?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84330\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"30\" role=\"region\" aria-labelledby=\"elementor-tab-title-84330\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Tutti i nostri ospiti provengono dalla nostra zona, il che significa che sono tutti raggiungibili a piedi o con un brevissimo viaggio in autobus dalla scuola. Questo garantisce che siano membri della comunit\u00e0 locale, cosa che riteniamo molto importante. Visitiamo tutte le famiglie ospitanti e ci assicuriamo che le loro case siano adatte a ospitare gli studenti. Ci assicuriamo inoltre che tutti i membri delle famiglie siano controllati dalla Garda e monitoriamo continuamente i feedback per assicurarci di lavorare solo con padroni di casa accoglienti e premurosi.   <\/p>\n<\/div>\n<\/div>\n<div class=\"exp-col-content-holder\"> <\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84331\" class=\"elementor-tab-title\" data-tab=\"31\" role=\"button\" aria-controls=\"elementor-tab-content-84331\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Mio figlio condivider\u00e0 la stanza nella famiglia ospitante?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84331\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"31\" role=\"region\" aria-labelledby=\"elementor-tab-title-84331\"><p>La maggior parte degli alloggi dispone di camere doppie, ma alcuni hanno anche camere singole o triple. Puoi richiedere che il tuo bambino condivida la stanza con un altro bambino, oppure se preferisci una stanza singola puoi richiedere anche questo e faremo del nostro meglio per soddisfare queste richieste. Gli studenti possono condividere la loro stanza con uno o pi\u00f9 studenti dello stesso sesso e di et\u00e0 simile. La maggior parte delle famiglie ospita 2 o 3 studenti alla volta.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84332\" class=\"elementor-tab-title\" data-tab=\"32\" role=\"button\" aria-controls=\"elementor-tab-content-84332\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Mio figlio star\u00e0 con un altro studente della stessa nazionalit\u00e0 o della stessa lingua?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84332\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"32\" role=\"region\" aria-labelledby=\"elementor-tab-title-84332\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p>I bambini vengono affidati a una sola nazionalit\u00e0 per famiglia, a meno che non chiedano di alloggiare con un amico della stessa nazionalit\u00e0. Possono tuttavia verificarsi brevi sovrapposizioni di famiglie della stessa nazionalit\u00e0, in caso di cambio di volo, ecc. <\/p>\n<p>Possiamo organizzare il soggiorno di un bambino con un amico, su richiesta al momento della prenotazione.<\/p>\n<p>Per i gruppi, gli studenti vengono inseriti in un mix di singoli e coppie su richiesta.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84333\" class=\"elementor-tab-title\" data-tab=\"33\" role=\"button\" aria-controls=\"elementor-tab-content-84333\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Posso prenotare una notte in pi\u00f9?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84333\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"33\" role=\"region\" aria-labelledby=\"elementor-tab-title-84333\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p>S\u00ec, una notte in pi\u00f9 costa 42 euro per facilitare i voli. Se \u00e8 richiesta pi\u00f9 di una notte, per i giorni in pi\u00f9 si applica l&#8217;intera tariffa del campo e gli studenti parteciperanno al nostro campo. <\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84334\" class=\"elementor-tab-title\" data-tab=\"34\" role=\"button\" aria-controls=\"elementor-tab-content-84334\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Come fanno i bambini ad andare e tornare dalla famiglia ospitante?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84334\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"34\" role=\"region\" aria-labelledby=\"elementor-tab-title-84334\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Gli studenti possono andare e tornare da scuola a piedi (nel raggio di 30 minuti) o prendere un breve viaggio in autobus. Poich\u00e9 la maggior parte dei programmi prevede un abbonamento di viaggio, gli studenti possono anche prendere un autobus locale per qualche fermata se preferiscono non camminare. <\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84335\" class=\"elementor-tab-title\" data-tab=\"35\" role=\"button\" aria-controls=\"elementor-tab-content-84335\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Tutti i soggiorni in casa sono in lingua inglese?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84335\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"35\" role=\"region\" aria-labelledby=\"elementor-tab-title-84335\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">S\u00ec, sono tutti anglofoni.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84336\" class=\"elementor-tab-title\" data-tab=\"36\" role=\"button\" aria-controls=\"elementor-tab-content-84336\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Cosa succede la domenica quando non ci sono attivit\u00e0 organizzate?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84336\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"36\" role=\"region\" aria-labelledby=\"elementor-tab-title-84336\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">La domenica \u00e8 un giorno libero per rilassarsi, chiediamo alle famiglie e agli studenti di trascorrere almeno una parte della giornata insieme partecipando alla normale routine familiare; gli studenti sono anche liberi di incontrarsi con gli amici, ma devono rimanere nella loro localit\u00e0 e non andare nella citt\u00e0 di Dublino.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84337\" class=\"elementor-tab-title\" data-tab=\"37\" role=\"button\" aria-controls=\"elementor-tab-content-84337\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Gli amici possono stare insieme in famiglia e durante le attivit\u00e0?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84337\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"37\" role=\"region\" aria-labelledby=\"elementor-tab-title-84337\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">S\u00ec, basta segnalarlo al momento della prenotazione come richiesta speciale.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84338\" class=\"elementor-tab-title\" data-tab=\"38\" role=\"button\" aria-controls=\"elementor-tab-content-84338\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ti occupi di diete speciali?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84338\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"38\" role=\"region\" aria-labelledby=\"elementor-tab-title-84338\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">S\u00ec, siamo in grado di soddisfare alcune diete speciali, ma \u00e8 sufficiente verificare con noi prima della prenotazione e a volte verr\u00e0 applicato un supplemento. Tieni presente che le famiglie ospitanti non gestiscono cucine professionali e quindi non possono ospitare studenti con gravi allergie o esigenze alimentari complesse. <\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84339\" class=\"elementor-tab-title\" data-tab=\"39\" role=\"button\" aria-controls=\"elementor-tab-content-84339\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Mio figlio pu\u00f2 prendere direttamente un taxi dall'aeroporto alla famiglia ospitante se non optiamo per i trasferimenti dall'aeroporto?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84339\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"39\" role=\"region\" aria-labelledby=\"elementor-tab-title-84339\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">S\u00ec, la scelta \u00e8 tua. Tuttavia, per motivi di sicurezza, consigliamo a tutti i bambini di farsi accompagnare dal nostro servizio di trasferimento aeroportuale. Inoltre, l&#8217;Ufficio Immigrazione dell&#8217;aeroporto di Dublino prevede che tutti i bambini di et\u00e0 inferiore ai 18 anni debbano essere accolti da qualcuno all&#8217;aeroporto di Dublino.  <\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84340\" class=\"elementor-tab-title\" data-tab=\"40\" role=\"button\" aria-controls=\"elementor-tab-content-84340\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Posso consegnare direttamente il mio bambino alla famiglia ospitante?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84340\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"40\" role=\"region\" aria-labelledby=\"elementor-tab-title-84340\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p>S\u00ec, coordineremo un orario tra te e il loro ospite.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-84341\" class=\"elementor-tab-title\" data-tab=\"41\" role=\"button\" aria-controls=\"elementor-tab-content-84341\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Che tipo di certificato ricever\u00e0 mio figlio al termine del corso?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-84341\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"41\" role=\"region\" aria-labelledby=\"elementor-tab-title-84341\"><div class=\"exp-col-content-holder\">\n<div class=\"hidden-content\">\n<p class=\"hiddenContentp\">Tuo figlio ricever\u00e0 un certificato di partecipazione e frequenza e una relazione individuale degli insegnanti sui suoi progressi.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-7cd714d1\" data-id=\"7cd714d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-420d1723 elementor-section-stretched brochures elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"420d1723\" data-element_type=\"section\" data-e-type=\"section\" id=\"brochures\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;shape_divider_top&quot;:&quot;mountains&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a5061a2\" data-id=\"1a5061a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7c94fc19 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c94fc19\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-312d186d\" data-id=\"312d186d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67977601 elementor-invisible elementor-widget elementor-widget-global elementor-global-33367 elementor-global-20831 elementor-widget-image\" data-id=\"67977601\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/online.fliphtml5.com\/fbxmh\/oaos\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1086\" src=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Irish-College-of-English-Junior-Summer-Camp-Brochure-2026-768x1086.jpg\" class=\"attachment-medium_large size-medium_large wp-image-29761\" alt=\"\" srcset=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Irish-College-of-English-Junior-Summer-Camp-Brochure-2026-768x1086.jpg 768w, https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Irish-College-of-English-Junior-Summer-Camp-Brochure-2026-212x300.jpg 212w, https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Irish-College-of-English-Junior-Summer-Camp-Brochure-2026-724x1024.jpg 724w, https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Irish-College-of-English-Junior-Summer-Camp-Brochure-2026-1086x1536.jpg 1086w, https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/Irish-College-of-English-Junior-Summer-Camp-Brochure-2026.jpg 1414w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-98943ac\" data-id=\"98943ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2abe55ae e-transform elementor-invisible elementor-widget elementor-widget-global elementor-global-34904 elementor-global-20834 elementor-widget-image\" data-id=\"2abe55ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInRight&quot;,&quot;_transform_scaleX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/online.fliphtml5.com\/fbxmh\/koxb\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"596\" height=\"843\" src=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Courses-and-Fees-2026-1.png\" class=\"attachment-medium_large size-medium_large wp-image-30260\" alt=\"\" srcset=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Courses-and-Fees-2026-1.png 596w, https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Courses-and-Fees-2026-1-212x300.png 212w\" sizes=\"(max-width: 596px) 100vw, 596px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c6aac3e elementor-align-center elementor-widget elementor-widget-global elementor-global-33376 elementor-global-20828 elementor-widget-button\" data-id=\"2c6aac3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl elementor-animation-grow\" href=\"https:\/\/www.bookingiceireland.com\/\" target=\"_blank\" id=\"enroll\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Iscriviti ora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ef209f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ef209f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b39eb04\" data-id=\"b39eb04\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Programma Classic Junior 2026 Dublino &#8211; Irlanda,15 giugno &#8211; 23 agosto11 &#8211; 17 anniProgramma di soggiorno in casa in inglese e multiattivit\u00e0 Il nostro Programma Classico \u00e8 il nostro fiore all&#8217;occhiello tra i campi estivi di inglese e attira il maggior numero di studenti. Si basa su una solida base accademica e la progressione \u00e8 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":18969,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"content-type":"","footnotes":""},"class_list":["post-32131","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campo estivo di inglese a Dublino 2023 - Collegio irlandese di inglese<\/title>\n<meta name=\"description\" content=\"Junior English Summer Camp Dublino - giugno, luglio, agosto 2024. Et\u00e0: 11 - 17 anni. Una scuola di inglese pluripremiata nella splendida Malahide, sulla costa di Dublino.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campo estivo di inglese a Dublino 2023 - Collegio irlandese di inglese\" \/>\n<meta property=\"og:description\" content=\"Junior English Summer Camp Dublino - giugno, luglio, agosto 2024. Et\u00e0: 11 - 17 anni. Una scuola di inglese pluripremiata nella splendida Malahide, sulla costa di Dublino.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iceireland.com\/it\/campo-estivo-inglese-irlanda\/english-summer-camp-dublin\/\" \/>\n<meta property=\"og:site_name\" content=\"Irish College of English\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-29T14:04:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-21.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/it\\\/campo-estivo-inglese-irlanda\\\/english-summer-camp-dublin\\\/\",\"url\":\"https:\\\/\\\/www.iceireland.com\\\/it\\\/campo-estivo-inglese-irlanda\\\/english-summer-camp-dublin\\\/\",\"name\":\"Campo estivo di inglese a Dublino 2023 - Collegio irlandese di inglese\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/it\\\/campo-estivo-inglese-irlanda\\\/english-summer-camp-dublin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/it\\\/campo-estivo-inglese-irlanda\\\/english-summer-camp-dublin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iceireland.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/ICE-Summer-Camp-2026-Banner-Photos-21.png\",\"datePublished\":\"2014-10-20T08:58:06+00:00\",\"dateModified\":\"2026-04-29T14:04:01+00:00\",\"description\":\"Junior English Summer Camp Dublino - giugno, luglio, agosto 2024. Et\u00e0: 11 - 17 anni. Una scuola di inglese pluripremiata nella splendida Malahide, sulla costa di Dublino.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/it\\\/campo-estivo-inglese-irlanda\\\/english-summer-camp-dublin\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.iceireland.com\\\/it\\\/campo-estivo-inglese-irlanda\\\/english-summer-camp-dublin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/it\\\/campo-estivo-inglese-irlanda\\\/english-summer-camp-dublin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.iceireland.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/ICE-Summer-Camp-2026-Banner-Photos-21.png\",\"contentUrl\":\"https:\\\/\\\/www.iceireland.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/ICE-Summer-Camp-2026-Banner-Photos-21.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/it\\\/campo-estivo-inglese-irlanda\\\/english-summer-camp-dublin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.iceireland.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campo estivo internazionale in inglese per ragazzi\",\"item\":\"https:\\\/\\\/www.iceireland.com\\\/it\\\/campo-estivo-inglese-irlanda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Campi estivi di inglese classico in Irlanda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.iceireland.com\\\/it\\\/\",\"name\":\"Irish College of English\",\"description\":\"English School in Dublin, Malahide\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.iceireland.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/it\\\/#organization\",\"name\":\"Irish College of English\",\"url\":\"https:\\\/\\\/www.iceireland.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.iceireland.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.iceireland.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/logo.png\",\"width\":593,\"height\":92,\"caption\":\"Irish College of English\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iceireland.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campo estivo di inglese a Dublino 2023 - Collegio irlandese di inglese","description":"Junior English Summer Camp Dublino - giugno, luglio, agosto 2024. Et\u00e0: 11 - 17 anni. Una scuola di inglese pluripremiata nella splendida Malahide, sulla costa di Dublino.","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Campo estivo di inglese a Dublino 2023 - Collegio irlandese di inglese","og_description":"Junior English Summer Camp Dublino - giugno, luglio, agosto 2024. Et\u00e0: 11 - 17 anni. Una scuola di inglese pluripremiata nella splendida Malahide, sulla costa di Dublino.","og_url":"https:\/\/www.iceireland.com\/it\/campo-estivo-inglese-irlanda\/english-summer-camp-dublin\/","og_site_name":"Irish College of English","article_modified_time":"2026-04-29T14:04:01+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-21.png","type":"image\/png"}],"twitter_misc":{"Tempo di lettura stimato":"13 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.iceireland.com\/it\/campo-estivo-inglese-irlanda\/english-summer-camp-dublin\/","url":"https:\/\/www.iceireland.com\/it\/campo-estivo-inglese-irlanda\/english-summer-camp-dublin\/","name":"Campo estivo di inglese a Dublino 2023 - Collegio irlandese di inglese","isPartOf":{"@id":"https:\/\/www.iceireland.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.iceireland.com\/it\/campo-estivo-inglese-irlanda\/english-summer-camp-dublin\/#primaryimage"},"image":{"@id":"https:\/\/www.iceireland.com\/it\/campo-estivo-inglese-irlanda\/english-summer-camp-dublin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-21.png","datePublished":"2014-10-20T08:58:06+00:00","dateModified":"2026-04-29T14:04:01+00:00","description":"Junior English Summer Camp Dublino - giugno, luglio, agosto 2024. Et\u00e0: 11 - 17 anni. Una scuola di inglese pluripremiata nella splendida Malahide, sulla costa di Dublino.","breadcrumb":{"@id":"https:\/\/www.iceireland.com\/it\/campo-estivo-inglese-irlanda\/english-summer-camp-dublin\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.iceireland.com\/it\/campo-estivo-inglese-irlanda\/english-summer-camp-dublin\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.iceireland.com\/it\/campo-estivo-inglese-irlanda\/english-summer-camp-dublin\/#primaryimage","url":"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-21.png","contentUrl":"https:\/\/www.iceireland.com\/wp-content\/uploads\/2025\/08\/ICE-Summer-Camp-2026-Banner-Photos-21.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.iceireland.com\/it\/campo-estivo-inglese-irlanda\/english-summer-camp-dublin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.iceireland.com\/it\/"},{"@type":"ListItem","position":2,"name":"Campo estivo internazionale in inglese per ragazzi","item":"https:\/\/www.iceireland.com\/it\/campo-estivo-inglese-irlanda\/"},{"@type":"ListItem","position":3,"name":"Campi estivi di inglese classico in Irlanda"}]},{"@type":"WebSite","@id":"https:\/\/www.iceireland.com\/it\/#website","url":"https:\/\/www.iceireland.com\/it\/","name":"Irish College of English","description":"English School in Dublin, Malahide","publisher":{"@id":"https:\/\/www.iceireland.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iceireland.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.iceireland.com\/it\/#organization","name":"Irish College of English","url":"https:\/\/www.iceireland.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.iceireland.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.iceireland.com\/wp-content\/uploads\/2022\/03\/logo.png","contentUrl":"https:\/\/www.iceireland.com\/wp-content\/uploads\/2022\/03\/logo.png","width":593,"height":92,"caption":"Irish College of English"},"image":{"@id":"https:\/\/www.iceireland.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.iceireland.com\/it\/wp-json\/wp\/v2\/pages\/32131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iceireland.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.iceireland.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.iceireland.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iceireland.com\/it\/wp-json\/wp\/v2\/comments?post=32131"}],"version-history":[{"count":4,"href":"https:\/\/www.iceireland.com\/it\/wp-json\/wp\/v2\/pages\/32131\/revisions"}],"predecessor-version":[{"id":36598,"href":"https:\/\/www.iceireland.com\/it\/wp-json\/wp\/v2\/pages\/32131\/revisions\/36598"}],"up":[{"embeddable":true,"href":"https:\/\/www.iceireland.com\/it\/wp-json\/wp\/v2\/pages\/18969"}],"wp:attachment":[{"href":"https:\/\/www.iceireland.com\/it\/wp-json\/wp\/v2\/media?parent=32131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}